{"id":13586,"date":"2023-12-10T16:56:38","date_gmt":"2023-12-10T19:56:38","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/10\/governo-da-franca-oferece-bolsas-para-estudantes-brasileiros\/"},"modified":"2023-12-10T16:56:38","modified_gmt":"2023-12-10T19:56:38","slug":"governo-da-franca-oferece-bolsas-para-estudantes-brasileiros","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/10\/governo-da-franca-oferece-bolsas-para-estudantes-brasileiros\/","title":{"rendered":"Governo da Fran\u00e7a oferece bolsas para estudantes brasileiros"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O Minist\u00e9rio de Rela\u00e7\u00f5es Exteriores e Desenvolvimento Internacional da Fran\u00e7a anunciou as inscri\u00e7\u00f5es para as bolsas Eiffel. O programa concede a <a href=\"https:\/\/catracalivre.com.br\/educacao\/universidade-da-suecia-oferece-bolsas-a-estudantes-brasileiros\/\" target=\"_blank\" rel=\"noopener\">estudantes estrangeiros<\/a> bolsas de estudo para realizar mestrado ou doutorado no pa\u00eds. As inscri\u00e7\u00f5es v\u00e3o at\u00e9 10 de janeiro de 2024.<\/p>\n<p>Os benef\u00edcios variam de acordo com o n\u00edvel de forma\u00e7\u00e3o dos alunos. Os estudantes de mestrado recebem \u20ac 1.181 (R$ 6.325) mensais; os de doutorado, \u20ac 1.700 R$ 9,106).<\/p>\n<div id=\"attachment_2301643\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2301643\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"querbeet\/iStock\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-2301643 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/10\/bolsas-de-estudo-franca-910x596.jpg?resize=910%2C596&#038;ssl=1\" alt=\"Governo da Fran\u00e7a oferece bolsas para estudantes brasileiros\" width=\"910\" height=\"596\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/10\/bolsas-de-estudo-franca-910x596.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/10\/bolsas-de-estudo-franca-450x295.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/10\/bolsas-de-estudo-franca-768x503.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: querbeet\/iStock<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Governo da Fran\u00e7a oferece bolsas para estudantes brasileiros<\/span><\/p>\n<\/div>\n<p>Tamb\u00e9m est\u00e3o inclusas no apoio financeiro as passagens a\u00e9reas, seguro sa\u00fade e ajuda de custo para atividades culturais.<\/p>\n<h2>O que as bolsas n\u00e3o cobrem<\/h2>\n<p>A\u00a0bolsa de estudo\u00a0n\u00e3o inclui a anuidade da universidade, mas os estudantes contemplados tamb\u00e9m podem se candidatar paralelamente a bolsas oferecidas pela institui\u00e7\u00e3o.<\/p>\n<p>Para se ter uma ideia, em institui\u00e7\u00f5es p\u00fablicas, os valores de anuidade podem totalizar, em m\u00e9dia, de \u20ac 200 a \u20ac 400.<\/p>\n<p>Para acessar a lista de cursos dispon\u00edveis, basta acessar o\u00a0site oficial do <a href=\"http:\/\/www.bresil.campusfrance.org\/\" target=\"_blank\" rel=\"noopener\">Campus France<\/a>. H\u00e1 ainda outras oportunidades de\u00a0bolsas de estudo <a href=\"https:\/\/catracalivre.com.br\/educacao\/universidade-da-suecia-oferece-bolsas-a-estudantes-brasileiros\/\" target=\"_blank\" rel=\"noopener\">para brasileiros<\/a>.<\/p>\n<h2>Como se inscrever para as bolsas Eiffel<\/h2>\n<p>Os candidatos \u00e0s bolsas de mestrado devem ter at\u00e9 25 anos de idade na data do programa (ou seja, nascidos ap\u00f3s mar\u00e7o de 1998) e os de doutorado, at\u00e9 30 (nascidos ap\u00f3s mar\u00e7o de 1993). Mais informa\u00e7\u00f5es\u00a0aqui.<\/p>\n<p>As\u00a0bolsas de estudo na Fran\u00e7a\u00a0s\u00e3o oferecidas diretamente \u00e0s universidades francesas. O primeiro passo, no entanto, \u00e9 enviar\u00a0a candidatura aos programas de interesse.<\/p>\n<p>Uma vez admitidos, os candidatos devem manifestar \u00e0 escola o desejo de concorrer \u00e0s bolsas Eiffel.\u00a0 Para atender ao prazo, as institui\u00e7\u00f5es devem encaminhar as candidaturas ao Campus France de Paris at\u00e9 o dia 10 de janeiro de 2024.<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/educacao\/governo-da-franca-oferece-bolsas-para-estudantes-brasileiros\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Minist\u00e9rio de Rela\u00e7\u00f5es Exteriores e Desenvolvimento Internacional da Fran\u00e7a anunciou as inscri\u00e7\u00f5es para as bolsas Eiffel. O programa concede a estudantes estrangeiros bolsas de estudo para realizar mestrado ou doutorado no pa\u00eds. As inscri\u00e7\u00f5es v\u00e3o at\u00e9 10 de janeiro de 2024. Os benef\u00edcios variam de acordo com o n\u00edvel de forma\u00e7\u00e3o dos alunos. &#8230; <a title=\"Governo da Fran\u00e7a oferece bolsas para estudantes brasileiros\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/10\/governo-da-franca-oferece-bolsas-para-estudantes-brasileiros\/\" aria-label=\"Leia mais sobre Governo da Fran\u00e7a oferece bolsas para estudantes brasileiros\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":13587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-13586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-franca.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Minist\u00e9rio de Rela\u00e7\u00f5es Exteriores e Desenvolvimento Internacional da Fran\u00e7a anunciou as inscri\u00e7\u00f5es para as bolsas Eiffel. O programa concede a estudantes estrangeiros bolsas de estudo para realizar mestrado ou doutorado no pa\u00eds. As inscri\u00e7\u00f5es v\u00e3o at\u00e9 10 de janeiro de 2024. Os benef\u00edcios variam de acordo com o n\u00edvel de forma\u00e7\u00e3o dos alunos.&hellip;","jetpack-related-posts":[{"id":11939,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/universidade-de-oxford-oferece-200-bolsas-para-pos-graduacao\/","url_meta":{"origin":13586,"position":0},"title":"Universidade de Oxford oferece 200 bolsas para p\u00f3s-gradua\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Universidade de Oxford, no Reino Unido, est\u00e3o com inscri\u00e7\u00f5es abertas para o programa da bolsas de estudo Clarendon. A iniciativa apoia candidatos de mestrado e de doutorado de qualquer \u00e1rea do conhecimento, que tenham desempenho acad\u00eamico excelente. Anualmente, s\u00e3o cerca 200 bolsas para p\u00f3s-gradua\u00e7\u00e3o concedidas a estudantes do\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/oxford-university.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/oxford-university.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/oxford-university.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/oxford-university.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/oxford-university.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":19343,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/universidade-de-lion-oferece-bolsas-para-mestrado-na-franca\/","url_meta":{"origin":13586,"position":1},"title":"Universidade de Lion oferece bolsas para mestrado na Fran\u00e7a","author":"ismaelcolosi.com.br","date":"22 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Universit\u00e9 de Lyon, na Fran\u00e7a, oferece anualmente cerca de 20 bolsas de estudo para estudantes internacionais que desejam cursar um programa de mestrado em ci\u00eancias exatas, artes, ci\u00eancias humanas e sociais na institui\u00e7\u00e3o. As oportunidades s\u00e3o para a\u00a0\u00c9cole Normale Sup\u00e9rieure (ENS) de Lyon, uma institui\u00e7\u00e3o p\u00fablica tradicional francesa\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/universite-de-lyon.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/universite-de-lyon.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/universite-de-lyon.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/universite-de-lyon.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/universite-de-lyon.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10178,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/03\/uniao-europeia-tem-programa-de-bolsas-para-brasileiros\/","url_meta":{"origin":13586,"position":2},"title":"Uni\u00e3o Europeia tem programa de bolsas para brasileiros","author":"ismaelcolosi.com.br","date":"3 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O programa Erasmus, promovido pela Uni\u00e3o Europeia para fomento a educa\u00e7\u00e3o, forma\u00e7\u00e3o, apoio a juventude e esportes, est\u00e1 com inscri\u00e7\u00f5es abertas para a edi\u00e7\u00e3o 2024\/25 do Erasmus Mundus Joint Master Degree (EMJMD). Estudantes que desejam fazer um mestrado internacional, incluindo brasileiros, podem concorrer a bolsas de estudo integrais em\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-uniao-europeia.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-uniao-europeia.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-uniao-europeia.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-uniao-europeia.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudo-uniao-europeia.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10256,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/universidade-da-suecia-oferece-bolsas-a-estudantes-brasileiros\/","url_meta":{"origin":13586,"position":3},"title":"Universidade da Su\u00e9cia oferece bolsas a estudantes brasileiros","author":"ismaelcolosi.com.br","date":"4 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Chalmers Unviersity of Technology est\u00e1 oferecendo 35 bolsas de mestrado na Su\u00e9cia para estudantes estrangeiros. As inscri\u00e7\u00f5es abrem\u00a0 v\u00e3o at\u00e9 15 de janeiro. As bolsas, parte do seu programa IPOET Scholarships, s\u00e3o v\u00e1lidas para todos os quase 40 programas de mestrado ministrados na institui\u00e7\u00e3o, todos com dura\u00e7\u00e3o de\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudos-suecia.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudos-suecia.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudos-suecia.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudos-suecia.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/bolsas-de-estudos-suecia.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":76502,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/13\/universidades-publicas-paulistas-implantam-novo-modelo-na-pos-graduacao\/","url_meta":{"origin":13586,"position":4},"title":"Universidades p\u00fablicas paulistas implantam novo modelo na p\u00f3s-gradua\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"13 de Novembro de 2024","format":false,"excerpt":"[ad_1] A partir de 2025, os programas de p\u00f3s-gradua\u00e7\u00e3o de excel\u00eancia das seis universidades p\u00fablicas paulistas, com notas 6 ou 7 na avalia\u00e7\u00e3o da Coordenadoria de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (Capes), poder\u00e3o adotar mudan\u00e7as estruturantes no modelo de seus cursos de p\u00f3s-gradua\u00e7\u00e3o. Essas mudan\u00e7as t\u00eam o objetivo de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/20241111_pos-graduacao-scaled.jpg?fit=800%2C420&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/20241111_pos-graduacao-scaled.jpg?fit=800%2C420&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/20241111_pos-graduacao-scaled.jpg?fit=800%2C420&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/20241111_pos-graduacao-scaled.jpg?fit=800%2C420&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":12893,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/universidade-sueca-oferece-35-bolsas-de-estudo-veja-como-se-inscrever\/","url_meta":{"origin":13586,"position":5},"title":"Universidade sueca oferece 35 bolsas de estudo; veja como se inscrever","author":"ismaelcolosi.com.br","date":"8 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: iStock\/Trygve FinkelsenChalmers Unviersity of Technology oferece bolsas de estudo \u00d3tima not\u00edcia para estudantes que sonham em realizar um mestrado em uma institui\u00e7\u00e3o estrangeira de alto n\u00edvel: a Chalmers University of Technology, na Su\u00e9cia, est\u00e1 oferecendo 35 vagas de bolsas para mestrado. As inscri\u00e7\u00f5es j\u00e1 est\u00e3o abertas e ser\u00e3o\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1311521507-scaled.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1311521507-scaled.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1311521507-scaled.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1311521507-scaled.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1311521507-scaled.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3x8","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13586"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/13587"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}