{"id":12953,"date":"2023-12-08T21:11:03","date_gmt":"2023-12-09T00:11:03","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/mulher-e-presa-por-ameacar-vereador-da-regiao\/"},"modified":"2023-12-08T21:11:03","modified_gmt":"2023-12-09T00:11:03","slug":"mulher-e-presa-por-ameacar-vereador-da-regiao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/mulher-e-presa-por-ameacar-vereador-da-regiao\/","title":{"rendered":"Mulher \u00e9 presa por amea\u00e7ar vereador da regi\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-366678\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<h2 class=\"penci-post-subtitle\">Motivo foi descumprimento de medida cautelar decretada pela Justi\u00e7a, determinando que ela n\u00e3o podia se aproximar da v\u00edtima<\/h2>\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-08T16:48:20-03:00\">8 de dezembro de 2023 | 16:48<\/time><time class=\"updated\" datetime=\"2023-12-08T16:52:27-03:00\">8 de dezembro de 2023 | 16:52<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"366678\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">2<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Mulher%20\u00e9%20presa%20por%20amea\u00e7ar%20vereador%20da%20regi\u00e3o%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/mulher-e-presa-por-ameacar-vereador-da-regiao\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>Por: Adalberto Luque<\/p>\n<p>Uma mulher foi presa na cidade de Cravinhos, na manh\u00e3 desta sexta-feira (08), por descumprir medida cautelar que a impedia de se aproximar de um vereador da cidade. Ela foi alvo de um inqu\u00e9rito de extors\u00e3o, persegui\u00e7\u00e3o e amea\u00e7a ao vereador, instaurado pela Pol\u00edcia Civil.<\/p>\n<p>Segundo o delegado de Cravinhos, Jorge Miguel Koury Neto, a mulher teria sido indiciada pelos crimes contra o vereador, que n\u00e3o teve o nome revelado. Ela teria inclusive, colidido com seu carro contra o carro do vereador pressionando e amea\u00e7ando os familiares da v\u00edtima. O delegado explicou que ela pedia dinheiro e fazia outras exig\u00eancias. Ela teria trabalhado para o vereador por algum tempo.<\/p>\n<p>\u201cEla foi denunciada, foi pedida uma medida cautelar para que ela se afastasse, sem comunica\u00e7\u00e3o com a v\u00edtima. Ela infringiu a medida cautelar e continuou amea\u00e7ando. A ju\u00edza decretou a pris\u00e3o preventiva dela por descumprimento da medida do Artigo 319 do C\u00f3digo de Processo Penal\u201d, explicou Koury Neto.<\/p>\n<p>Ao cumprir o mandado de pris\u00e3o por descumprimento da medida cautelar, os policiais civis encontraram a mulher se preparando para fugir. Ela foi presa e encaminhada \u00e0 cadeia p\u00fablica de Franca, de onde seguiria para um Centro de Deten\u00e7\u00e3o Provis\u00f3ria (CDP), permanecendo \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/mulher-e-presa-por-ameacar-vereador-da-regiao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] Motivo foi descumprimento de medida cautelar decretada pela Justi\u00e7a, determinando que ela n\u00e3o podia se aproximar da v\u00edtima 8 de dezembro de 2023 | 16:488 de dezembro de 2023 | 16:52 2 Por: Adalberto Luque Uma mulher foi presa na cidade de Cravinhos, na manh\u00e3 desta sexta-feira (08), por descumprir medida cautelar que a &#8230; <a title=\"Mulher \u00e9 presa por amea\u00e7ar vereador da regi\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/mulher-e-presa-por-ameacar-vereador-da-regiao\/\" aria-label=\"Leia mais sobre Mulher \u00e9 presa por amea\u00e7ar vereador da regi\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":12954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1791,325,134,182,277,1792],"class_list":["post-12953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-ameacar","tag-mulher","tag-por","tag-presa","tag-regiao","tag-vereador"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=968%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=968%2C645&ssl=1",968,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=968%2C645&ssl=1",968,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Fachada-delegacia-Cravinhos-Foto-Alfredo-Risk-02-scaled.jpg?fit=968%2C645&ssl=1",968,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] Motivo foi descumprimento de medida cautelar decretada pela Justi\u00e7a, determinando que ela n\u00e3o podia se aproximar da v\u00edtima 8 de dezembro de 2023 | 16:488 de dezembro de 2023 | 16:52 2 Por: Adalberto Luque Uma mulher foi presa na cidade de Cravinhos, na manh\u00e3 desta sexta-feira (08), por descumprir medida cautelar que a&hellip;","jetpack-related-posts":[{"id":41193,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/06\/homem-e-preso-na-regiao-apos-ameacar-mulher-com-faca\/","url_meta":{"origin":12953,"position":0},"title":"Homem \u00e9 preso na regi\u00e3o ap\u00f3s amea\u00e7ar mulher com faca","author":"ismaelcolosi.com.br","date":"6 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] V\u00edtima teria registrado boletim de ocorr\u00eancia horas antes por amea\u00e7a a sua filha 6 de mar\u00e7o de 2024 | 16:34 2Por: Adalberto LuqueUm homem foi preso, na tarde desta ter\u00e7a-feira (05), ap\u00f3s amea\u00e7ar esfaquear uma mulher. O fato ocorreu na cidade de Cravinhos, horas depois que a mulher registrou\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-06-fev-2024-maria-da-penha-cravinhos-foto-policia-civil-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-06-fev-2024-maria-da-penha-cravinhos-foto-policia-civil-scaled.jpg?fit=1000%2C563&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-06-fev-2024-maria-da-penha-cravinhos-foto-policia-civil-scaled.jpg?fit=1000%2C563&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/00-06-fev-2024-maria-da-penha-cravinhos-foto-policia-civil-scaled.jpg?fit=1000%2C563&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":54503,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/06\/25\/empresario-e-preso-acusado-de-agredir-e-ameacar-a-mulher-na-regiao-de-ribeirao-preto\/","url_meta":{"origin":12953,"position":1},"title":"Empres\u00e1rio \u00e9 preso acusado de agredir e amea\u00e7ar a mulher na regi\u00e3o de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"25 de Junho de 2024","format":false,"excerpt":"[ad_1] Um empres\u00e1rio, de 43 anos, foi preso ap\u00f3s ser denunciado por viol\u00eancia dom\u00e9stica na noite desta segunda-feira (24), em Monte Alto, cidade na regi\u00e3o de Ribeir\u00e3o Preto. De acordo com o boletim de ocorr\u00eancia (BO), equipes da Pol\u00edcia Militar (PM) foram acionadas pela esposa do acusado, ap\u00f3s uma discuss\u00e3o\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/06\/WhatsApp-Image-2023-12-23-at-12.01.31.jpeg?fit=480%2C245&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":18758,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/20\/idoso-e-preso-por-trafico-de-mulheres-e-estupro-de-vulneravel-na-regiao\/","url_meta":{"origin":12953,"position":2},"title":"Idoso \u00e9 preso por tr\u00e1fico de mulheres e estupro de vulner\u00e1vel na regi\u00e3o","author":"ismaelcolosi.com.br","date":"20 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Funcion\u00e1rio p\u00fablico aposentado explorava sexualmente pelo menos quatro mulheres e uma adolescente 20 de dezembro de 2023 | 16:3820 de dezembro de 2023 | 16:39 2Por: Adalberto LuqueUm funcion\u00e1rio p\u00fablico aposentado de 61 anos foi preso, na manh\u00e3 desta ter\u00e7a-feira (20), em Batatais. Ele \u00e9 investigado por tr\u00e1fico de\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-20-dez-2023-exploracao-sexual-batatais-foto-google-street-reproducao-scaled.jpg?fit=1000%2C561&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-20-dez-2023-exploracao-sexual-batatais-foto-google-street-reproducao-scaled.jpg?fit=1000%2C561&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-20-dez-2023-exploracao-sexual-batatais-foto-google-street-reproducao-scaled.jpg?fit=1000%2C561&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/00-20-dez-2023-exploracao-sexual-batatais-foto-google-street-reproducao-scaled.jpg?fit=1000%2C561&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":57516,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/07\/22\/mulher-e-presa-no-interior-de-sp-apos-confusao-com-faca-em-hospital\/","url_meta":{"origin":12953,"position":3},"title":"Mulher \u00e9 presa no interior de SP ap\u00f3s confus\u00e3o com faca em hospital","author":"ismaelcolosi.com.br","date":"22 de Julho de 2024","format":false,"excerpt":"[ad_1] Uma mulher de 32 anos, que estava armada com uma faca, foi presa em Guariba, no interior de S\u00e3o Paulo, depois de amea\u00e7ar funcion\u00e1rios de um hospital com uma faca, na noite do \u00faltimo s\u00e1bado (20). A mulher tamb\u00e9m quebrou o vidro da viatura da pol\u00edcia. Segundo a mulher,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/faca-guariba_2024-07-22_15-32-12_jpeg_2024-07-22_15-32-12.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/faca-guariba_2024-07-22_15-32-12_jpeg_2024-07-22_15-32-12.webp.webp?fit=1200%2C674&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/faca-guariba_2024-07-22_15-32-12_jpeg_2024-07-22_15-32-12.webp.webp?fit=1200%2C674&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/faca-guariba_2024-07-22_15-32-12_jpeg_2024-07-22_15-32-12.webp.webp?fit=1200%2C674&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/07\/faca-guariba_2024-07-22_15-32-12_jpeg_2024-07-22_15-32-12.webp.webp?fit=1200%2C674&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":37911,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/02\/19\/homem-e-preso-em-ribeirao-preto-acusado-de-sequestrar-mulher-dentro-de-onibus\/","url_meta":{"origin":12953,"position":4},"title":"Homem \u00e9 preso em Ribeir\u00e3o Preto acusado de sequestrar mulher dentro de \u00f4nibus","author":"ismaelcolosi.com.br","date":"19 de Fevereiro de 2024","format":false,"excerpt":"[ad_1] A Pol\u00edcia Militar prendeu em Ribeir\u00e3o Preto um homem de 27 anos acusado de sequestro, estupro e extors\u00e3o por uma mulher de 31 anos. A v\u00edtima e o suspeito estavam dentro de um \u00f4nibus que partiu do Rio de Janeiro, no \u00faltimo domingo (18), e que tinha como destino\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/02\/cpj_1024x576_04082020121137.jpg?fit=1024%2C575&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":20230,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/24\/atas-secretas-da-camara-foram-abertas-em-1998\/","url_meta":{"origin":12953,"position":5},"title":"\u2018Atas Secretas\u2019 da C\u00e2mara foram abertas em 1998\u00a0","author":"ismaelcolosi.com.br","date":"24 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 24 de dezembro de 2023 | 16:0024 de dezembro de 2023 | 11:07 0As atas secretas da C\u00e2mara Municipal de Ribeir\u00e3o Preto retratam as sess\u00f5es realizadas entre as d\u00e9cadas de 1940 e 1970. Elas se tornaram p\u00fablicas no dia 5 de agosto de 1998. Estavam dentro de um cofre,\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/ata-fazer-uma-montagem-1-scaled.jpg?fit=458%2C645&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3mV","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12953"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/12954"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}