{"id":12922,"date":"2023-12-08T20:09:49","date_gmt":"2023-12-08T23:09:49","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/balneario-camboriu-ganha-maior-parque-de-dinossauros-do-brasil\/"},"modified":"2023-12-08T20:09:49","modified_gmt":"2023-12-08T23:09:49","slug":"balneario-camboriu-ganha-maior-parque-de-dinossauros-do-brasil","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/balneario-camboriu-ganha-maior-parque-de-dinossauros-do-brasil\/","title":{"rendered":"Balne\u00e1rio Cambori\u00fa ganha maior parque de dinossauros do Brasil"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O Brasil tem um novo parque tem\u00e1tico. A nova atra\u00e7\u00e3o, localizada em <a href=\"https:\/\/catracalivre.com.br\/viagem-livre\/brasil-tera-a-maior-temporada-de-cruzeiros-dos-ultimos-11-anos\/\" target=\"_blank\" rel=\"noopener\">Balne\u00e1rio Cambori\u00fa<\/a> (SC), um dos principais destinos tur\u00edsticos do sul do pa\u00eds, j\u00e1 \u00e9 considerada uma das maiores do mundo quando o assunto s\u00e3o os dinossauros.<\/p>\n<p>Aberto ao p\u00fablico no final de setembro, o <a href=\"https:\/\/ingresso.aventurajurassica.com.br\/\" target=\"_blank\" rel=\"noopener\">Aventura Jur\u00e1ssica<\/a> fica em um terreno de 100 mil metros quadrados de vegeta\u00e7\u00e3o preservada, sendo 30 mil de \u00e1rea constru\u00edda.<\/p>\n<div id=\"attachment_2320028\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2320028\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Divulga\u00e7\u00e3o\" fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-2320028 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-910x512.jpg?resize=910%2C512&#038;ssl=1\" alt=\"O Aventura Jur\u00e1ssica fica em Balne\u00e1rio Cambori\u00fa (SC)\" width=\"910\" height=\"512\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-910x512.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-450x253.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-768x432.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Divulga\u00e7\u00e3o<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">O Aventura Jur\u00e1ssica fica em Balne\u00e1rio Cambori\u00fa (SC)<\/span><\/p>\n<\/div>\n<p>O parque foi criado com o objetivo de ser uma divers\u00e3o para toda a fam\u00edlia, tendo um roteiro de passeio que leva o visitante a conhecer desde a origem animal, antes do surgimento dos vertebrados, at\u00e9 os gigantescos animais que dominaram a terra milhares de anos atr\u00e1s.<\/p>\n<h2>Atra\u00e7\u00f5es do Aventura Jur\u00e1ssica<\/h2>\n<p>Fruto de um investimento de mais de R$ 60 milh\u00f5es, o Aventura Jur\u00e1ssica conta com cerca de 80 esp\u00e9cies e mais de 100 animais em exposi\u00e7\u00e3o, tra\u00e7ando uma linha hist\u00f3rica que vai do surgimento \u00e0 extin\u00e7\u00e3o dos dinossauros.<\/p>\n<div id=\"attachment_2320029\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2320029\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Divulga\u00e7\u00e3o\" decoding=\"async\" class=\"wp-image-2320029 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica2-910x512.jpeg?resize=910%2C512&#038;ssl=1\" alt=\"A maior parte dos animais s\u00e3o\u00a0Animatr\u00f4micos, todos em tamanhos reais\" width=\"910\" height=\"512\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica2-910x512.jpeg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica2-450x253.jpeg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica2-768x432.jpeg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Divulga\u00e7\u00e3o<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">A maior parte dos animais s\u00e3o\u00a0Animatr\u00f4micos, todos em tamanhos reais<\/span><\/p>\n<\/div>\n<p>A visita ao parque come\u00e7a com uma exposi\u00e7\u00e3o de f\u00f3sseis de organismos anteriores ao surgimento dos vertebrados como s\u00e3o conhecidos, de r\u00e9pteis ancestrais e dos animais que deram origem aos mam\u00edferos.<\/p>\n<p>Entre as pe\u00e7as de destaque, encontra-se um f\u00f3ssil original de um exemplar inteiro de um dos r\u00e9pteis mais antigos, o Mesossauro, e tamb\u00e9m f\u00f3sseis originais de Dicinodontes \u2013anteriores aos dinossauros e mam\u00edferos.<\/p>\n<div id=\"attachment_2320030\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2320030\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Divulga\u00e7\u00e3o\" decoding=\"async\" class=\"wp-image-2320030 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-ovos-dinos-910x512.jpg?resize=910%2C512&#038;ssl=1\" alt=\"Aventura Jur\u00e1ssica conta com cerca de 80 esp\u00e9cies e mais de 100 animais em exposi\u00e7\u00e3o\" width=\"910\" height=\"512\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-ovos-dinos-910x512.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-ovos-dinos-450x253.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-ovos-dinos-768x432.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Divulga\u00e7\u00e3o<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">Aventura Jur\u00e1ssica conta com cerca de 80 esp\u00e9cies e mais de 100 animais em exposi\u00e7\u00e3o<\/span><\/p>\n<\/div>\n<p>Outros itens raros em exposi\u00e7\u00e3o s\u00e3o um ovo original de Hadrossauro, mand\u00edbulas originais de tr\u00eas esp\u00e9cies de Mosassauros, o grande r\u00e9ptil marinho \u2013sensa\u00e7\u00e3o do filme \u201cJurassic World\u201d\u2013 e asas originais de Pterossauros com 107 milh\u00f5es de anos coletados no Brasil.<\/p>\n<p>A maior parte dos animais s\u00e3o\u00a0Animatr\u00f4micos, todos em tamanhos reais, que se movimentam e reproduzem rugidos, fazendo do passeio uma verdadeira experi\u00eancia na pr\u00e9-hist\u00f3ria.<\/p>\n<h3>Dinossauros brasileiros<\/h3>\n<p>O visitante fica imerso em um verdadeiro\u00a0Jardim Mesoz\u00f3ico, um ambiente \u00fanico e nunca reproduzido desta forma.<\/p>\n<p>As mais antigas s\u00e3o as esp\u00e9cies brasileiras, entre elas o Macrocollum, o Pampadromadeus e o Buriolestes tamb\u00e9m pode ser visto no parque.<\/p>\n<div id=\"attachment_2320031\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2320031\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Divulga\u00e7\u00e3o\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-2320031 size-large\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/img-1469-910x512.jpg?resize=910%2C512&#038;ssl=1\" alt=\"O Aventura Jur\u00e1ssica conta ainda com parque de divers\u00f5es para crian\u00e7as\" width=\"910\" height=\"512\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/img-1469-910x512.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/img-1469-450x253.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/img-1469-768x432.jpg 768w\" sizes=\"auto, (max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Divulga\u00e7\u00e3o<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">O Aventura Jur\u00e1ssica conta ainda com parque de divers\u00f5es para crian\u00e7as<\/span><\/p>\n<\/div>\n<p>O maior dinossauro do Aventura Jur\u00e1ssica \u00e9 do per\u00edodo Cret\u00e1ceo: o Argentinossauro, com cerca de 35 metros de comprimento e dez de altura, que tem como vizinho um imponente T-Rex, com seus 25 metros de comprimento e 8 metros de altura.<\/p>\n<p>O parque conta ainda com playground in e outdoor, labirinto, passeio de barco, fonte interativa, arvorismo com cerca de 80 metros de altura, mirante, \u00e1rea para descanso, lanchonetes e restaurante tem\u00e1tico, al\u00e9m da tirolesa que atravessa o parque, do mirante ao vulc\u00e3o.<\/p>\n<p><strong>Aventura Jur\u00e1ssica<\/strong><br \/><strong>Onde<\/strong>: Rua Aqueduto, 360, Estados, Balne\u00e1rio Cambori\u00fa SC<br \/>Quanto: a partir de R$ 99,90. Crian\u00e7as de 0 a 4 anos n\u00e3o pagam<br \/><strong>Hor\u00e1rios<\/strong>: segunda a sexta, 9h \u00e0s 18h (bilheteria funciona at\u00e9 16h); s\u00e1bados, domingos e feriados das 9h \u00e0s 19h (bilheteria funciona at\u00e9 17h)<br \/><strong>Informa\u00e7\u00f5es<\/strong>: Tel.: (47) 3311-7000<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/viagem-livre\/fotos-balneario-camboriu-ganha-maior-parque-de-dinossauros-do-brasil\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Brasil tem um novo parque tem\u00e1tico. A nova atra\u00e7\u00e3o, localizada em Balne\u00e1rio Cambori\u00fa (SC), um dos principais destinos tur\u00edsticos do sul do pa\u00eds, j\u00e1 \u00e9 considerada uma das maiores do mundo quando o assunto s\u00e3o os dinossauros. Aberto ao p\u00fablico no final de setembro, o Aventura Jur\u00e1ssica fica em um terreno de 100&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":12923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-12922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?fit=1200%2C638&ssl=1",1200,638,true],"neve-blog":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/aventura-jurassica-sc-scaled.jpg?resize=930%2C620&ssl=1",930,620,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Brasil tem um novo parque tem\u00e1tico. A nova atra\u00e7\u00e3o, localizada em Balne\u00e1rio Cambori\u00fa (SC), um dos principais destinos tur\u00edsticos do sul do pa\u00eds, j\u00e1 \u00e9 considerada uma das maiores do mundo quando o assunto s\u00e3o os dinossauros. Aberto ao p\u00fablico no final de setembro, o Aventura Jur\u00e1ssica fica em um terreno de 100&hellip;&nbsp;","jetpack-related-posts":[{"id":22004,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/29\/atracoes-que-voce-precisa-conhecer-em-balneario-camboriu-sc\/","url_meta":{"origin":12922,"position":0},"title":"Atra\u00e7\u00f5es que voc\u00ea precisa conhecer em Balne\u00e1rio Cambori\u00fa (SC)","author":"ismaelcolosi.com.br","date":"29 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Balne\u00e1rio Cambori\u00fa, no litoral norte de Santa Catarina, est\u00e1 entre os destinos de praia mais procurados do Brasil para a virada do ano. S\u00e3o esperados cerca de 2 milh\u00f5es de turistas, segundo proje\u00e7\u00e3o da Secretaria Municipal de Turismo da cidade. Al\u00e9m das badaladas festas, Balne\u00e1rio Cambori\u00fa ter\u00e1 um in\u00e9dito\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":17975,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/19\/praia-alargada-de-balneario-camboriu-esta-100-impropria-para-banho\/","url_meta":{"origin":12922,"position":1},"title":"Praia alargada de Balne\u00e1rio Cambori\u00fa est\u00e1 100% impr\u00f3pria para banho","author":"ismaelcolosi.com.br","date":"19 de Dezembro de 2023","format":false,"excerpt":"[ad_1] \u00c0s v\u00e9speras da temporada de ver\u00e3o, a badalada Balne\u00e1rio Cambori\u00fa (SC) tem sua principal praia impr\u00f3pria para banho de mar em toda sua extens\u00e3o. A praia Central passou pela megaobra de alargamento no final de 2021 e, desde ent\u00e3o, vem apresentando condi\u00e7\u00f5es inadequadas de balneabilidade. Cr\u00e9ditos: Element Films\/Divulga\u00e7\u00e3oVista a\u00e9rea\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu-praia-central-pontal-norte.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu-praia-central-pontal-norte.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu-praia-central-pontal-norte.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu-praia-central-pontal-norte.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/balneario-camboriu-praia-central-pontal-norte.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":25348,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/06\/sc-lancha-com-8-pessoas-a-bordo-pega-fogo-diante-de-praia-lotada\/","url_meta":{"origin":12922,"position":2},"title":"SC: Lancha com 8 pessoas a bordo pega fogo diante de praia lotada","author":"ismaelcolosi.com.br","date":"6 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Neste s\u00e1bado (6), uma embarca\u00e7\u00e3o foi consumida por um inc\u00eandio em pleno mar de Balne\u00e1rio Cambori\u00fa, diante de\u00a0dezenas de turistas que aproveitava o dia ensolarado.A lancha pegou fogo na Praia Central, situada em Balne\u00e1rio Cambori\u00fa, na regi\u00e3o litor\u00e2nea do Norte de Santa Catarina. Conforme informa\u00e7\u00f5es da Pol\u00edcia Militar, oito\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6599f79c34bb99971.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6599f79c34bb99971.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6599f79c34bb99971.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6599f79c34bb99971.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6599f79c34bb99971.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":19298,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/22\/destinos-proximos-a-sp-para-o-ano-novo\/","url_meta":{"origin":12922,"position":3},"title":"destinos pr\u00f3ximos a SP para o Ano Novo","author":"ismaelcolosi.com.br","date":"22 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O ano est\u00e1 acabando e, com 2024 batendo \u00e0 porta, aumenta tamb\u00e9m a procura pelos chamados \u201cdestinos de escapada\u201d para o Ano Novo. Para quem mora em S\u00e3o Paulo, s\u00e3o destinos geralmente mais pr\u00f3ximos \u00e0 capital, onde \u00e9 poss\u00edvel pensar em uma programa\u00e7\u00e3o completa para passar poucos dias ou\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-522619781.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-522619781.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-522619781.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-522619781.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-522619781.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":22269,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/29\/parana-tem-94-das-praias-proprias-para-banho-de-mar\/","url_meta":{"origin":12922,"position":4},"title":"Paran\u00e1 tem 94% das praias pr\u00f3prias para banho de mar","author":"ismaelcolosi.com.br","date":"29 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Turistas que v\u00e3o passar o Ano Novo nas praias do Paran\u00e1 v\u00e3o encontrar \u00e1guas com condi\u00e7\u00f5es pr\u00f3prias para o banho de mar. De acordo com boletim de balneabilidade do Instituto \u00c1gua e Terra (IAT), divulgado nesta quinta-feira, 28, aponta que 94% das praias do estado est\u00e3o pr\u00f3prias para banho.\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/praia-ilha-do-mel.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/praia-ilha-do-mel.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/praia-ilha-do-mel.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/praia-ilha-do-mel.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/praia-ilha-do-mel.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":24448,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/04\/velorio-coletivo-marca-a-despedida-dos-quatro-jovens-que-foram-encontrados-mortos-em-bmw-video-causa-comocao\/","url_meta":{"origin":12922,"position":5},"title":"Vel\u00f3rio coletivo marca a despedida dos quatro jovens que foram encontrados mortos em BMW; v\u00eddeo causa como\u00e7\u00e3o","author":"ismaelcolosi.com.br","date":"4 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Na localidade de Paracatu, em Minas Gerais, ap\u00f3s mais de doze horas de atraso, quatro fam\u00edlias finalmente conseguiram se reencontrar e se despedir de seus entes queridos nesta \u00faltima quarta-feira, dia 3 de janeiro, no Jockey Clube local.Os corpos os quatro jovens, encontrados mortos no primeiro dia do ano\u2026","rel":"","context":"In &quot;Blog&quot;","block_context":{"text":"Blog","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/blog\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6596ce45efdf67527.jpg?fit=1200%2C628&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6596ce45efdf67527.jpg?fit=1200%2C628&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6596ce45efdf67527.jpg?fit=1200%2C628&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6596ce45efdf67527.jpg?fit=1200%2C628&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/postimg-6596ce45efdf67527.jpg?fit=1200%2C628&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-3mq","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12922"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12922\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/12923"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}