{"id":12118,"date":"2023-12-07T13:11:43","date_gmt":"2023-12-07T16:11:43","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/voo-de-repatriacao-de-brasileiros-em-gaza-aguarda-autorizacao\/"},"modified":"2023-12-07T13:11:43","modified_gmt":"2023-12-07T16:11:43","slug":"voo-de-repatriacao-de-brasileiros-em-gaza-aguarda-autorizacao","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/voo-de-repatriacao-de-brasileiros-em-gaza-aguarda-autorizacao\/","title":{"rendered":"Voo de repatria\u00e7\u00e3o de brasileiros em Gaza aguarda autoriza\u00e7\u00e3o"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"post-366498\">\n<header class=\"entry-header penci-entry-header penci-title-center\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-07T13:00:30-03:00\">7 de dezembro de 2023 | 13:00<\/time><time class=\"updated\" datetime=\"2023-12-07T09:03:41-03:00\">7 de dezembro de 2023 | 9:03<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"366498\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Voo%20de%20repatria\u00e7\u00e3o%20de%20brasileiros%20em%20Gaza%20aguarda%20autoriza\u00e7\u00e3o%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/voo-de-repatriacao-de-brasileiros-em-gaza-aguarda-autorizacao\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/header>\n<div class=\"penci-entry-content entry-content\">\n<p>Uma aeronave KC-30 (Airbus A330 200) aguarda autoriza\u00e7\u00e3o para decolar da Base A\u00e9rea do Gale\u00e3o, no Rio de Janeiro, para fazer a repatria\u00e7\u00e3o de mais brasileiros que est\u00e3o na Faixa de Gaza. De acordo com a For\u00e7a A\u00e9rea Brasileira (FAB), o avi\u00e3o s\u00f3 decolar\u00e1 rumo ao Egito quando os brasileiros tiverem permiss\u00e3o para cruzar a fronteira\u00a0em Rafah.\u00a0<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\"\/><\/noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\"\/><\/noscript><\/p>\n<p>Assim que receber o sinal verde, o KC-30 decolar\u00e1 rumo ao Aeroporto Internacional do Cairo, em uma viagem de 15 horas. A FAB ainda n\u00e3o divulgou o n\u00famero de pessoas\u00a0que ser\u00e3o repatriadas.<\/p>\n<p>O avi\u00e3o tamb\u00e9m leva um carregamento de cerca de 11 toneladas de alimentos n\u00e3o perec\u00edveis, fornecidos como assist\u00eancia humanit\u00e1ria pelo governo brasileiro.<\/p>\n<p>O primeiro voo de repatria\u00e7\u00e3o de brasileiros provenientes de Gaza s\u00f3 chegou ao Brasil no dia 15 de novembro, mais de um m\u00eas depois do in\u00edcio dos ataques de Israel ao territ\u00f3rio palestino, devido \u00e0 demora na autoriza\u00e7\u00e3o para sa\u00edda pelo posto de fronteira de Rafah, que liga Gaza ao Egito.<\/p>\n<p>No total, 32 brasileiros, segundo a FAB, foram trazidos ao pa\u00eds nesse voo. Tamb\u00e9m foi realizado um voo de repatria\u00e7\u00e3o com 32 brasileiros que estavam na Cisjord\u00e2nia, outro territ\u00f3rio palestino.<\/p>\n<p>Antes deles, j\u00e1 haviam sido realizados oito voos de repatria\u00e7\u00e3o de 1.413 brasileiros que estavam em Israel.<\/p>\n<\/div>\n<footer class=\"penci-entry-footer\"\/><\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/voo-de-repatriacao-de-brasileiros-em-gaza-aguarda-autorizacao\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 7 de dezembro de 2023 | 13:007 de dezembro de 2023 | 9:03 0 Uma aeronave KC-30 (Airbus A330 200) aguarda autoriza\u00e7\u00e3o para decolar da Base A\u00e9rea do Gale\u00e3o, no Rio de Janeiro, para fazer a repatria\u00e7\u00e3o de mais brasileiros que est\u00e3o na Faixa de Gaza. De acordo com a For\u00e7a A\u00e9rea Brasileira (FAB), &#8230; <a title=\"Voo de repatria\u00e7\u00e3o de brasileiros em Gaza aguarda autoriza\u00e7\u00e3o\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/voo-de-repatriacao-de-brasileiros-em-gaza-aguarda-autorizacao\/\" aria-label=\"Leia mais sobre Voo de repatria\u00e7\u00e3o de brasileiros em Gaza aguarda autoriza\u00e7\u00e3o\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":12119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1690,1691,200,1208,1689,1688],"class_list":["post-12118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-aguarda","tag-autorizacao","tag-brasileiros","tag-gaza","tag-repatriacao","tag-voo"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=1000%2C598&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=300%2C179&ssl=1",300,179,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=768%2C459&ssl=1",768,459,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-scaled.jpg?fit=1000%2C598&ssl=1",1000,598,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 7 de dezembro de 2023 | 13:007 de dezembro de 2023 | 9:03 0 Uma aeronave KC-30 (Airbus A330 200) aguarda autoriza\u00e7\u00e3o para decolar da Base A\u00e9rea do Gale\u00e3o, no Rio de Janeiro, para fazer a repatria\u00e7\u00e3o de mais brasileiros que est\u00e3o na Faixa de Gaza. De acordo com a For\u00e7a A\u00e9rea Brasileira (FAB),&hellip;","jetpack-related-posts":[{"id":13142,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/voo-para-resgate-de-mais-brasileiros-em-gaza-decola-para-o-egito\/","url_meta":{"origin":12118,"position":0},"title":"Voo para resgate de mais brasileiros em Gaza decola para o Egito","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 9 de dezembro de 2023 | 10:18 0O voo que aguardava no Rio de Janeiro\u00a0para resgatar mais brasileiros que est\u00e3o na Faixa de Gaza decolou no in\u00edcio da manh\u00e3 deste s\u00e1bado (9)\u00a0em dire\u00e7\u00e3o ao Egito, informou a For\u00e7a A\u00e9rea Brasileira (FAB). Este ser\u00e1 o 11\u00ba\u00a0voo de repatria\u00e7\u00e3o de brasileiros\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/fab-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1376,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/12\/brasileiros-cruzam-a-fronteira-de-gaza-com-o-egito\/","url_meta":{"origin":12118,"position":1},"title":"Brasileiros cruzam a fronteira de Gaza com o Egito","author":"ismaelcolosi.com.br","date":"12 de Novembro de 2023","format":false,"excerpt":"[ad_1] 12 de novembro de 2023 | 11:36 0Depois de um m\u00eas de agonia, um grupo de 32 brasileiros que aguardava repatria\u00e7\u00e3o em Gaza conseguiu cruzar a fronteira com o Egito, pelo Portal de Rafah. Eles fizeram a passagem no in\u00edcio da manh\u00e3 deste domingo (12), de acordo com postagem\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileiros-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileiros-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileiros-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileiros-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1525,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/13\/brasileiros-que-estavam-em-gaza-chegam-nesta-segunda-ao-brasil\/","url_meta":{"origin":12118,"position":2},"title":"Brasileiros que estavam em Gaza chegam nesta segunda ao Brasil","author":"ismaelcolosi.com.br","date":"13 de Novembro de 2023","format":false,"excerpt":"[ad_1] Os brasileiros e seus familiares palestinos que\u00a0deixaram a Faixa de Gaza\u00a0chegam nesta segunda-feira (13) ao Brasil. O governo federal j\u00e1 tem uma opera\u00e7\u00e3o de acolhimento pronta para o grupo, como atendimento m\u00e9dico e psicol\u00f3gico e regulariza\u00e7\u00e3o de documentos.\u00a0Eles\u00a0cruzaram a fronteira\u00a0com o Egito\u00a0pelo Portal de Rafah, no in\u00edcio da manh\u00e3\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/criancas-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1071,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/10\/brasileiros-em-gaza-estao-na-fronteira-com-egito-aguardando-passagem\/","url_meta":{"origin":12118,"position":3},"title":"Brasileiros em Gaza est\u00e3o na fronteira com Egito aguardando passagem","author":"ismaelcolosi.com.br","date":"10 de Novembro de 2023","format":false,"excerpt":"[ad_1] 10 de novembro de 2023 | 10:56 0O grupo dos brasileiros que est\u00e3o na Faixa de Gaza aguarda, desde o in\u00edcio da manh\u00e3 desta sexta-feira (10), a possibilidade de atravessar a fronteira de Rafah, com o Egito. A autoriza\u00e7\u00e3o para deixar o territ\u00f3rio palestino saiu ap\u00f3s 34 dias do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/gaza-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/gaza-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/gaza-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/gaza-1-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":1101,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/10\/fronteira-de-gaza-com-egito-e-fechada-e-brasileiros-ficam-retidos\/","url_meta":{"origin":12118,"position":4},"title":"Fronteira de Gaza com Egito \u00e9 fechada e brasileiros ficam retidos","author":"ismaelcolosi.com.br","date":"10 de Novembro de 2023","format":false,"excerpt":"[ad_1] 10 de novembro de 2023 | 12:0510 de novembro de 2023 | 11:58 0O ministro das Rela\u00e7\u00f5es Exteriores, Mauro Vieira, confirmou nesta sexta-feira (10) o fechamento da fronteira entre a Faixa de Gaza e o Egito \u2013 antes que o grupo\u00a0de 34 brasileiros pudesse\u00a0deixar o local.Ap\u00f3s mais de um\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileirogaza1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileirogaza1-scaled.jpg?fit=1000%2C598&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileirogaza1-scaled.jpg?fit=1000%2C598&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/brasileirogaza1-scaled.jpg?fit=1000%2C598&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8996,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/01\/israel-retoma-combate-em-gaza\/","url_meta":{"origin":12118,"position":5},"title":"Israel retoma combate em Gaza","author":"ismaelcolosi.com.br","date":"1 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 1 de dezembro de 2023 | 10:301 de dezembro de 2023 | 9:38 0O ex\u00e9rcito de Israel retomou as opera\u00e7\u00f5es de combate na Faixa de Gaza minutos ap\u00f3s o cessar-fogo com o Hamas expirar, nesta sexta-feira, 1. Jerusal\u00e9m acusa o grupo palestino de n\u00e3o ter respeitado a tr\u00e9gua, que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/israel.png?fit=627%2C400&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/israel.png?fit=627%2C400&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/israel.png?fit=627%2C400&ssl=1&resize=525%2C300 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-39s","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=12118"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/12118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/12119"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=12118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=12118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=12118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}