{"id":11945,"date":"2023-12-07T06:21:11","date_gmt":"2023-12-07T09:21:11","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/stf-toma-nova-decisao-sobre-vinculo-entre-motoristas-e-aplicativos\/"},"modified":"2023-12-07T06:21:11","modified_gmt":"2023-12-07T09:21:11","slug":"stf-toma-nova-decisao-sobre-vinculo-entre-motoristas-e-aplicativos","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/stf-toma-nova-decisao-sobre-vinculo-entre-motoristas-e-aplicativos\/","title":{"rendered":"STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>A Primeira Turma do Supremo Tribunal Federal (<a href=\"https:\/\/catracalivre.com.br\/stories\/o-que-faz-o-stf\/\" target=\"_blank\" rel=\"noopener\">STF<\/a>) decidiu nesta ter\u00e7a-feira, 5,\u00a0 que n\u00e3o h\u00e1 v\u00ednculo de emprego entre motoristas de <a href=\"https:\/\/catracalivre.com.br\/tag\/aplicativo\/\" target=\"_blank\" rel=\"noopener\">aplicativos<\/a>\u00a0e as empresas que operam as plataformas. O entendimento vale para todas as plataformas.<\/p>\n<div id=\"attachment_2273598\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2273598\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Rovena Rosa\/Ag\u00eancia Brasil\" fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-2273598\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/05\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao-910x544.jpg?resize=910%2C544&#038;ssl=1\" alt=\"STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos\" width=\"910\" height=\"544\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/05\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao-910x544.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/05\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao-450x269.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/05\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao-768x459.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Rovena Rosa\/Ag\u00eancia Brasil<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos<\/span><\/p>\n<\/div>\n<p>O colegiado julgou uma decis\u00e3o da <a href=\"https:\/\/portal.trt3.jus.br\/internet\" target=\"_blank\" rel=\"noopener\">Justi\u00e7a do Trabalho<\/a> de <a href=\"https:\/\/catracalivre.com.br\/viagem-livre\/5-destinos-na-natureza-pouco-explorados-em-minas-gerais\/\" target=\"_blank\" rel=\"noopener\">Minas Gerais<\/a> que reconheceu v\u00ednculo de <a href=\"https:\/\/catracalivre.com.br\/tag\/emprego\/\" target=\"_blank\" rel=\"noopener\">emprego<\/a> entre um motorista e a plataforma Cabify.<\/p>\n<p>Em seu voto, o relator do processo, ministro <a href=\"https:\/\/catracalivre.com.br\/cidadania\/moraes-toma-decisao-em-julgamento-sobre-revisao-da-vida-toda-do-inss\/\" target=\"_blank\" rel=\"noopener\">Alexandre de Moraes<\/a>, afirmou que a Justi\u00e7a Trabalhista tem descumprido reiteradamente precedentes do plen\u00e1rio do Supremo sobre a inexist\u00eancia de rela\u00e7\u00e3o de emprego entre as empresas de aplicativos e os motoristas.<\/p>\n<p>Para o ministro, a Constitui\u00e7\u00e3o admite outras rela\u00e7\u00f5es de trabalho. \u201cAquele que faz parte da Cabify, da <a href=\"https:\/\/catracalivre.com.br\/viagem-livre\/uber-oferece-viagens-gratis-para-atracoes-que-celebram-cultura-negra\/\" target=\"_blank\" rel=\"noopener\">Uber<\/a>, do <a href=\"https:\/\/catracalivre.com.br\/educacao\/ifood-abre-inscricoes-para-cursos-gratuitos-de-programacao\/\" target=\"_blank\" rel=\"noopener\">iFood<\/a>, ele tem a liberdade de aceitar as corridas que quer. Ele tem a liberdade de fazer o seu hor\u00e1rio e tem a liberdade de ter outros v\u00ednculos\u201d, justificou.<\/p>\n<p>O voto de Moraes foi seguido pelos ministros Cristiano Zanin, Luiz Fux e C\u00e1rmen Lucia.<\/p>\n<p>Apesar de n\u00e3o reconhecer o v\u00ednculo de emprego, C\u00e1rmen L\u00facia demonstrou preocupa\u00e7\u00e3o com o futuro dos trabalhadores e a falta de regulamenta\u00e7\u00e3o de direitos. \u201cNos preocupamos com esse modelo, o que n\u00e3o significa adotar o modelo da legisla\u00e7\u00e3o trabalhista como se fosse uma forma de resolver. N\u00e3o tenho d\u00favida de que, em 20 anos ou menos, teremos um grav\u00edssimo problema social e previdenci\u00e1rio. As pessoas que ficam nesse sistema de \u2018uberiza\u00e7\u00e3o\u2019 n\u00e3o t\u00eam os direitos sociais garantidos na Constitui\u00e7\u00e3o por aus\u00eancia de serem suportados por uma legisla\u00e7\u00e3o\u201d, afirmou.<\/p>\n<p>Durante o julgamento, o advogado M\u00e1rcio Eurico Vitral Amaro, representante da Cabify, alegou que o modelo de trabalho da empresa n\u00e3o pode ser considerado como rela\u00e7\u00e3o de emprego, nos moldes da\u00a0Consolida\u00e7\u00e3o das Leis do Trabalho (<a href=\"https:\/\/catracalivre.com.br\/cidadania\/clt\/\" target=\"_blank\" rel=\"noopener\">CLT<\/a>). Amaro ponderou que as mudan\u00e7as tecnol\u00f3gicas tamb\u00e9m refletiram no mercado de trabalho.<\/p>\n<p>\u201cAqueles conceitos cl\u00e1ssicos da rela\u00e7\u00e3o de emprego n\u00e3o se aplicam a essas novas formas de trabalho humano. Essas formas n\u00e3o cabem nos limitad\u00edssimos marcos e limites da CLT\u201d, afirmou.<\/p>\n<p><em>Com informa\u00e7\u00f5es da Ag\u00eancia Brasil.<\/em><\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/cidadania\/stf-toma-nova-decisao-sobre-vinculo-entre-motoristas-e-aplicativos\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] A Primeira Turma do Supremo Tribunal Federal (STF) decidiu nesta ter\u00e7a-feira, 5,\u00a0 que n\u00e3o h\u00e1 v\u00ednculo de emprego entre motoristas de aplicativos\u00a0e as empresas que operam as plataformas. O entendimento vale para todas as plataformas. Cr\u00e9ditos: Rovena Rosa\/Ag\u00eancia Brasil STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos O colegiado julgou uma decis\u00e3o &#8230; <a title=\"STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/stf-toma-nova-decisao-sobre-vinculo-entre-motoristas-e-aplicativos\/\" aria-label=\"Leia mais sobre STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":11946,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-11945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/pessima-noticia-para-motoristas-de-carro-por-aplicativo-gera-grande-apreensao.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] A Primeira Turma do Supremo Tribunal Federal (STF) decidiu nesta ter\u00e7a-feira, 5,\u00a0 que n\u00e3o h\u00e1 v\u00ednculo de emprego entre motoristas de aplicativos\u00a0e as empresas que operam as plataformas. O entendimento vale para todas as plataformas. Cr\u00e9ditos: Rovena Rosa\/Ag\u00eancia Brasil STF toma NOVA decis\u00e3o sobre v\u00ednculo entre motoristas e aplicativos O colegiado julgou uma decis\u00e3o&hellip;","jetpack-related-posts":[{"id":11677,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/decisao-do-stf-sobre-vinculo-entre-motoristas-e-aplicativos-surpreende\/","url_meta":{"origin":11945,"position":0},"title":"Decis\u00e3o do STF sobre v\u00ednculo entre motoristas e aplicativos SURPREENDE","author":"ismaelcolosi.com.br","date":"6 de Dezembro de 2023","format":false,"excerpt":"[ad_1] A Primeira Turma do Supremo Tribunal Federal (STF) decidiu nesta ter\u00e7a-feira, 5,\u00a0 que n\u00e3o h\u00e1 v\u00ednculo de emprego entre motoristas de aplicativos\u00a0e as empresas que operam as plataformas. O entendimento vale para todas as plataformas. Cr\u00e9ditos: Ag\u00eancia Brasil\/Marcello Casal JrDecis\u00e3o do STF sobre v\u00ednculo entre motoristas e aplicativos SURPREENDE\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/decisao-surpreendente-contra-uber-impacta-motoristas-de-aplicativo.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/decisao-surpreendente-contra-uber-impacta-motoristas-de-aplicativo.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/decisao-surpreendente-contra-uber-impacta-motoristas-de-aplicativo.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/decisao-surpreendente-contra-uber-impacta-motoristas-de-aplicativo.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/decisao-surpreendente-contra-uber-impacta-motoristas-de-aplicativo.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12218,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/plenario-do-stf-julgara-vinculo-com-aplicativo\/","url_meta":{"origin":11945,"position":1},"title":"Plen\u00e1rio do STF julgar\u00e1 v\u00ednculo com aplicativo\u00a0","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] 7 de dezembro de 2023 | 17:007 de dezembro de 2023 | 10:54 0A decis\u00e3o da Primeira Turma do Supremo Tribunal Federal (STF) que afastou v\u00ednculo de emprego entre um entregador e o aplicativo Cabify ser\u00e1 submetida ao plen\u00e1rio da Corte. \u00c9 a primeira vez que os ministros do\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/uber-scaled.jpg?fit=1000%2C616&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/uber-scaled.jpg?fit=1000%2C616&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/uber-scaled.jpg?fit=1000%2C616&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/uber-scaled.jpg?fit=1000%2C616&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":84556,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2025\/04\/14\/stf-suspende-acoes-do-pais-sobre-pejotizacao-de-profissionais\/","url_meta":{"origin":11945,"position":2},"title":"STF Suspende A\u00e7\u00f5es do Pa\u00eds sobre Pejotiza\u00e7\u00e3o de Profissionais","author":"ismaelcolosi.com.br","date":"14 de Abril de 2025","format":false,"excerpt":"[ad_1] \r Marcello Casal Jr\/Ag\u00eancia Brasil\/Arquivo\r Tema da pejotiza\u00e7\u00e3o tem colocado o Supremo em rota de colis\u00e3o com a Justi\u00e7a Trabalhista ao menos desde 2018\r Acessibilidade \r L\r L\r A-\r A+\r \r \u25d0\r \r \u00a0 O ministro Gilmar Mendes, do Supremo Tribunal Federal (STF), decidiu nesta segunda-feira (14) suspender a\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-STF-pejotizacao-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-STF-pejotizacao-1200x675.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-STF-pejotizacao-1200x675.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-STF-pejotizacao-1200x675.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2025\/04\/forbes-STF-pejotizacao-1200x675.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":75892,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/11\/08\/stf-permite-contratacao-de-servidores-publicos-pela-clt-sem-estabilidade-entenda-a-decisao-e-suas-implicacoes\/","url_meta":{"origin":11945,"position":3},"title":"STF Permite Contrata\u00e7\u00e3o de Servidores P\u00fablicos pela CLT Sem Estabilidade: Entenda a Decis\u00e3o e Suas Implica\u00e7\u00f5es","author":"ismaelcolosi.com.br","date":"8 de Novembro de 2024","format":false,"excerpt":"[ad_1] Nesta semana, o Supremo Tribunal Federal (STF) tomou uma decis\u00e3o hist\u00f3rica ao permitir a contrata\u00e7\u00e3o de servidores p\u00fablicos sob o regime da Consolida\u00e7\u00e3o das Leis do Trabalho (CLT), sem a tradicional estabilidade garantida aos servidores estatut\u00e1rios. A medida, aprovada por maioria de votos, altera a configura\u00e7\u00e3o dos v\u00ednculos empregat\u00edcios\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/IMG_9383.jpeg?fit=716%2C428&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/IMG_9383.jpeg?fit=716%2C428&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/IMG_9383.jpeg?fit=716%2C428&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/11\/IMG_9383.jpeg?fit=716%2C428&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":46838,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/04\/15\/diretor-juridico-que-representava-x-no-brasil-renuncia\/","url_meta":{"origin":11945,"position":4},"title":"Diretor jur\u00eddico que representava X no Brasil renuncia","author":"ismaelcolosi.com.br","date":"15 de Abril de 2024","format":false,"excerpt":"[ad_1] Em resposta a Alexandre de Moraes, o bilion\u00e1rio fundador da Tesla e dono do X atacou o ministro nas redes sociais O advogado Diego de Lima Gualda, diretor Jur\u00eddico do X (antigo Twitter), renunciou ao cargo na \u00faltima semana semana, segundo carta enviada \u00e0 Jucesp (Junta Comercial de S\u00e3o\u2026","rel":"","context":"In &quot;Carreira e Sucesso&quot;","block_context":{"text":"Carreira e Sucesso","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/carreira-e-sucesso-dicas-para-carreira\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/money-x-twitter-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/money-x-twitter-1024x683.jpg?fit=1024%2C683&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/money-x-twitter-1024x683.jpg?fit=1024%2C683&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/04\/money-x-twitter-1024x683.jpg?fit=1024%2C683&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":40593,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/04\/lula-assina-projeto-que-regula-atividade-de-motoristas-de-aplicativo\/","url_meta":{"origin":11945,"position":5},"title":"Lula assina projeto que regula atividade de motoristas de aplicativo","author":"ismaelcolosi.com.br","date":"4 de Mar\u00e7o de 2024","format":false,"excerpt":"[ad_1] O presidente Luiz In\u00e1cio Lula da Silva assinou nesta segunda-feira (4) a proposta de projeto de lei que regulamenta o trabalho de motorista de aplicativo. O texto do projeto de lei complementar ser\u00e1 enviado para vota\u00e7\u00e3o no Congresso Nacional. Caso seja aprovada pelos parlamentares, passar\u00e1 a valer ap\u00f3s 90\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/captura-de-tela-2024-03-03-141825.jpg?fit=800%2C551&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/captura-de-tela-2024-03-03-141825.jpg?fit=800%2C551&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/captura-de-tela-2024-03-03-141825.jpg?fit=800%2C551&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/captura-de-tela-2024-03-03-141825.jpg?fit=800%2C551&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-36F","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11945"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/11946"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}