{"id":11702,"date":"2023-12-06T17:31:33","date_gmt":"2023-12-06T20:31:33","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/governo-vai-prorrogar-programa-desenrola-por-mais-tres-meses\/"},"modified":"2023-12-06T17:31:33","modified_gmt":"2023-12-06T20:31:33","slug":"governo-vai-prorrogar-programa-desenrola-por-mais-tres-meses","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/governo-vai-prorrogar-programa-desenrola-por-mais-tres-meses\/","title":{"rendered":"Governo vai prorrogar Programa Desenrola por mais tr\u00eas meses"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div id=\"\">\n<p> <span class=\"entry-meta-item penci-posted-on\"><i class=\"fa fa-clock-o\"\/><time class=\"entry-date published\" datetime=\"2023-12-06T17:30:47-03:00\">6 de dezembro de 2023 | 17:30<\/time><time class=\"updated\" datetime=\"2023-12-06T14:03:19-03:00\">6 de dezembro de 2023 | 14:03<\/time><\/span><\/p>\n<p> <span class=\"penci-social-buttons penci-social-share-footer\"><a href=\"#\" class=\"penci-post-like penci_post-meta_item  single-like-button penci-social-item like\" data-post_id=\"366426\" title=\"Like\" data-like=\"Like\" data-unlike=\"Unlike\"><i class=\"fa fa-thumbs-o-up\"\/><span class=\"penci-share-number\">0<\/span><\/a><i class=\"fa fa-facebook\"\/><a class=\"penci-social-item twitter\" target=\"_blank\" rel=\"noopener\" title=\"\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Governo%20vai%20prorrogar%20Programa%20Desenrola%20por%20mais%20tr\u00eas%20meses%20-%20https:\/\/www.tribunaribeirao.com.br\/site\/governo-vai-prorrogar-programa-desenrola-por-mais-tres-meses\/\"><i class=\"fa fa-twitter\"\/><\/a><i class=\"fa fa-whatsapp\"\/><\/span><\/div>\n<div>\n<p>O governo federal vai prorrogar o Desenrola por mais tr\u00eas meses. O programa de renegocia\u00e7\u00e3o de d\u00edvidas termina no dia 31 de dezembro. Segundo informou hoje (6) o secret\u00e1rio de Reformas Econ\u00f4micas do Minist\u00e9rio da Fazenda, Marcos Barbosa Pinto, o governo vai mandar para o Congresso Nacional na pr\u00f3xima semana uma medida provis\u00f3ria estendendo o programa para os tr\u00eas primeiros meses de 2024 e, tamb\u00e9m, deve eliminar o requisito de ter uma conta Gov.br prata ou ouro para acessar a plataforma.<img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.png?w=1200&#038;ssl=1\"\/><\/noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\" class=\"lazyload\"\/><noscript><img data-recalc-dims=\"1\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/agenciabrasil.ebc.com.br\/ebc.gif?w=1200&#038;ssl=1\"\/><\/noscript><\/p><div class='code-block code-block-8' style='margin: 8px auto; text-align: center; display: block; clear: both;'>\n<script>\n  atOptions = {\n    'key' : '66e2e2111ca34da796271819fc334058',\n    'format' : 'iframe',\n    'height' : 250,\n    'width' : 300,\n    'params' : {}\n  };\n<\/script>\n<script src=\"https:\/\/www.highperformanceformat.com\/66e2e2111ca34da796271819fc334058\/invoke.js\"><\/script>\n<\/div>\n\n<p>O Desenrola abrange d\u00edvidas negativadas entre 1\u00ba de janeiro de 2019 e 31 de dezembro de 2022. \u201cA gente quer estender [o Desenrola] por mais alguns meses no ano seguinte, para tr\u00eas meses para a gente poder beneficiar toda a popula\u00e7\u00e3o\u201d, disse Pinto.<\/p>\n<p>De acordo com o secret\u00e1rio, o minist\u00e9rio est\u00e1 discutindo com os bancos e a B3 uma forma de suprimir o requisito de ter conta prata ou ouro, mas que mantenha o grau de seguran\u00e7a da plataforma. O objetivo \u00e9 facilitar o acesso de mais pessoas \u00e0 plataforma.<\/p>\n<p>\u201cA gente n\u00e3o acha que esse [grau prata ou ouro] seja o maior empecilho para as negocia\u00e7\u00f5es acontecerem num ritmo \u00f3timo, mas a gente acredita que \u00e9 um ponto que pode causar algum entrave para algumas pessoas. Ent\u00e3o a gente quer abrir m\u00e3o desse requisito e trabalhar com os bancos uma solu\u00e7\u00e3o de seguran\u00e7a\u201d, afirmou.<\/p>\n<p>O secret\u00e1rio disse que, ap\u00f3s o per\u00edodo de extens\u00e3o do programa, o governo estuda manter a plataforma do Desenrola no ar para que credores e devedores continuem a negociar, mas sem a garantia do Fundo Garantidor de Opera\u00e7\u00f5es (FGO), fundo do Tesouro Nacional que cobre eventuais calotes de quem aderir \u00e0 renegocia\u00e7\u00e3o.<\/p>\n<p>Desde o in\u00edcio de outubro, a\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2023-10\/consumidor-pode-renegociar-dividas-na-terceira-fase-do-desenrola\" target=\"_blank\" rel=\"noopener\">Faixa 1 do Desenrola<\/a>\u00a0renegocia d\u00edvidas de at\u00e9 R$ 5 mil na plataforma desenvolvida pela B3, no\u00a0<em><a href=\"http:\/\/www.desenrola.gov.br\/\" target=\"_blank\" rel=\"noopener\">site<\/a><\/em>. A portaria que regulamenta o programa define que, se ap\u00f3s os 40 primeiros dias, sobrar recursos no FGO, o refinanciamento seria ampliado para\u00a0<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2023-11\/desenrola-passa-renegociar-dividas-de-ate-r-20-mil\" target=\"_blank\" rel=\"noopener\">d\u00e9bitos de at\u00e9 R$ 20 mil<\/a>, como ocorre no momento.<\/p>\n<p>\u201cA gente n\u00e3o quer manter o fundo garantidor, mas quer manter a plataforma. A gente viu muita renegocia\u00e7\u00e3o de d\u00edvidas ocorrer \u00e0 vista e nos surpreendeu o volume. Como o valor das d\u00edvidas, em geral, \u00e9 pequeno, muitas vezes o credor quer dar desconto e o devedor, com aquele desconto, estaria disposto a fazer o pagamento, mas \u00e9 muito caro para eles se encontrarem dado o valor da d\u00edvida. A plataforma \u00e9 um legado que fica para a sociedade para se fazer isso\u201d, explicou.<\/p>\n<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.tribunaribeirao.com.br\/site\/governo-vai-prorrogar-programa-desenrola-por-mais-tres-meses\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] 6 de dezembro de 2023 | 17:306 de dezembro de 2023 | 14:03 0 O governo federal vai prorrogar o Desenrola por mais tr\u00eas meses. O programa de renegocia\u00e7\u00e3o de d\u00edvidas termina no dia 31 de dezembro. Segundo informou hoje (6) o secret\u00e1rio de Reformas Econ\u00f4micas do Minist\u00e9rio da Fazenda, Marcos Barbosa Pinto, o &#8230; <a title=\"Governo vai prorrogar Programa Desenrola por mais tr\u00eas meses\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/governo-vai-prorrogar-programa-desenrola-por-mais-tres-meses\/\" aria-label=\"Read more about Governo vai prorrogar Programa Desenrola por mais tr\u00eas meses\">Read more<\/a><\/p>\n","protected":false},"author":1,"featured_media":11703,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[714,1271,276,640,134,1071,1634,639,529],"class_list":["post-11702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-desenrola","tag-governo","tag-mais","tag-meses","tag-por","tag-programa","tag-prorrogar","tag-tres","tag-vai"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=967%2C645&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-1-scaled.jpg?fit=967%2C645&ssl=1",967,645,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] 6 de dezembro de 2023 | 17:306 de dezembro de 2023 | 14:03 0 O governo federal vai prorrogar o Desenrola por mais tr\u00eas meses. O programa de renegocia\u00e7\u00e3o de d\u00edvidas termina no dia 31 de dezembro. Segundo informou hoje (6) o secret\u00e1rio de Reformas Econ\u00f4micas do Minist\u00e9rio da Fazenda, Marcos Barbosa Pinto, o&hellip;","jetpack-related-posts":[{"id":12054,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/nao-negociou-divida-com-o-desenrola-a-melhor-noticia-acaba-de-chegar\/","url_meta":{"origin":11702,"position":0},"title":"N\u00e3o negociou d\u00edvida com o Desenrola? A melhor not\u00edcia acaba de chegar","author":"ismaelcolosi.com.br","date":"7 de December de 2023","format":false,"excerpt":"[ad_1] O governo federal vai prorrogar o Desenrola por mais tr\u00eas meses. O programa de renegocia\u00e7\u00e3o de d\u00edvidas termina no dia 31 de dezembro. Cr\u00e9ditos: iStock\/fizkesN\u00e3o negociou d\u00edvida com o Desenrola? A melhor not\u00edcia acaba de chegar Segundo informou o secret\u00e1rio de Reformas Econ\u00f4micas do Minist\u00e9rio da Fazenda, Marcos Barbosa\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1158702105-e1688579646196.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1158702105-e1688579646196.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1158702105-e1688579646196.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1158702105-e1688579646196.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1158702105-e1688579646196.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12494,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/desenrola-dara-chance-de-negociar-dividas-e-limpar-o-nome-em-2024\/","url_meta":{"origin":11702,"position":1},"title":"Desenrola dar\u00e1 chance de negociar d\u00edvidas e limpar o nome em 2024","author":"ismaelcolosi.com.br","date":"8 de December de 2023","format":false,"excerpt":"[ad_1] O governo federal vai prorrogar o Desenrola por mais tr\u00eas meses. O programa de renegocia\u00e7\u00e3o de d\u00edvidas termina no dia 31 de dezembro. Cr\u00e9ditos: Ag\u00eancia Brasil\/Marcello Casal JrDesenrola dar\u00e1 chance de negociar d\u00edvidas e limpar o nome em 2024 Segundo informou o secret\u00e1rio de Reformas Econ\u00f4micas do Minist\u00e9rio da\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702022724_dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702022724_dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702022724_dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702022724_dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702022724_dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14812,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/12\/programa-desenrola-e-prorrogado-por-tres-meses\/","url_meta":{"origin":11702,"position":2},"title":"Programa Desenrola \u00e9 prorrogado por tr\u00eas meses","author":"ismaelcolosi.com.br","date":"12 de December de 2023","format":false,"excerpt":"[ad_1] 12 de dezembro de 2023 | 14:3012 de dezembro de 2023 | 14:12 0O programa Desenrola foi prorrogado at\u00e9 31 de mar\u00e7o de 2024, tr\u00eas meses al\u00e9m do prazo inicial, que seria o fim deste ano. Medida provis\u00f3ria foi publicada nesta ter\u00e7a-feira (12) no\u00a0Di\u00e1rio Oficial da Uni\u00e3o., que altera\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-2.jpg?fit=940%2C623&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-2.jpg?fit=940%2C623&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-2.jpg?fit=940%2C623&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/desenrola-2.jpg?fit=940%2C623&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":11629,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/nova-chance-para-quem-esta-endividado-acaba-de-chegar\/","url_meta":{"origin":11702,"position":3},"title":"nova chance para quem est\u00e1 endividado ACABA DE CHEGAR","author":"ismaelcolosi.com.br","date":"6 de December de 2023","format":false,"excerpt":"[ad_1] O governo federal vai prorrogar o Desenrola por mais tr\u00eas meses. O programa de renegocia\u00e7\u00e3o de d\u00edvidas termina no dia 31 de dezembro. Cr\u00e9ditos: Jos\u00e9 Cruz\/Ag\u00eancia BrasilDesenrola: NOVA chance para quem est\u00e1 endividado ACABA DE CHEGAR Segundo informou o secret\u00e1rio de Reformas Econ\u00f4micas do Minist\u00e9rio da Fazenda, Marcos Barbosa\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/dividas-desenrola-brasil.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":44573,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/03\/28\/governo-publica-medida-provisoria-que-prorroga-desenrola-ate-20-de-maio\/","url_meta":{"origin":11702,"position":4},"title":"Governo publica medida provis\u00f3ria que prorroga Desenrola at\u00e9 20 de maio","author":"ismaelcolosi.com.br","date":"28 de March de 2024","format":false,"excerpt":"[ad_1] 28 de mar\u00e7o de 2024 | 15:0028 de mar\u00e7o de 2024 | 12:07 0 O presidente Luiz In\u00e1cio Lula da Silva publicou nesta quinta-feira, 28, no\u00a0Di\u00e1rio Oficial da Uni\u00e3o (DOU) uma medida provis\u00f3ria para prorrogar o Desenrola Brasil at\u00e9 o dia 20 de maio deste ano. Inicialmente previsto para\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/desenrola-e1701948869188.jpg?fit=700%2C402&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/desenrola-e1701948869188.jpg?fit=700%2C402&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/desenrola-e1701948869188.jpg?fit=700%2C402&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/03\/desenrola-e1701948869188.jpg?fit=700%2C402&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":4580,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/21\/mutirao-no-desenrola-vai-negociar-dividas-de-ate-r-20-mil-veja-quando\/","url_meta":{"origin":11702,"position":5},"title":"Mutir\u00e3o no Desenrola vai negociar d\u00edvidas de at\u00e9 R$ 20 mil; veja quando","author":"ismaelcolosi.com.br","date":"21 de November de 2023","format":false,"excerpt":"[ad_1] A partir desta segunda-feira, 20, o Programa Desenrola Brasil entra numa nova fase. A Faixa 1 do programa, destinada \u00e0 renegocia\u00e7\u00e3o a devedores com renda de at\u00e9 dois sal\u00e1rios m\u00ednimos ou inscritos no Cadastro \u00danico para Programas Sociais do Governo Federal (Cad\u00danico), passar\u00e1 a renegociar d\u00edvidas de at\u00e9 R$\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mutirao-no-desenrola-vai-negociar-dividas-de-ate-r-20-mil-veja-quando.png?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mutirao-no-desenrola-vai-negociar-dividas-de-ate-r-20-mil-veja-quando.png?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mutirao-no-desenrola-vai-negociar-dividas-de-ate-r-20-mil-veja-quando.png?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mutirao-no-desenrola-vai-negociar-dividas-de-ate-r-20-mil-veja-quando.png?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/mutirao-no-desenrola-vai-negociar-dividas-de-ate-r-20-mil-veja-quando.png?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-32K","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11702"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11702\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/11703"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}