{"id":11561,"date":"2023-12-06T12:27:07","date_gmt":"2023-12-06T15:27:07","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/saiba-como-ver-as-datas-das-carreatas-de-natal-da-coca-no-interior-de-sp\/"},"modified":"2023-12-06T12:27:07","modified_gmt":"2023-12-06T15:27:07","slug":"saiba-como-ver-as-datas-das-carreatas-de-natal-da-coca-no-interior-de-sp","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/saiba-como-ver-as-datas-das-carreatas-de-natal-da-coca-no-interior-de-sp\/","title":{"rendered":"Saiba como ver as datas das carreatas de Natal da Coca no interior de SP"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div data-td-block-uid=\"tdi_104\">\n<div class=\"tdb-block-inner td-fix-index\">\n<p>As tradicionais <strong>carreatas de Natal<\/strong>, organizadas pela Coca-Cola, j\u00e1 come\u00e7aram.<strong> Em Ribeir\u00e3o Preto, os desfiles est\u00e3o programados para os dias 11, 20 e 21 de dezembro.<\/strong><\/p>\n<p>No total, al\u00e9m de Ribeir\u00e3o Preto, treze cidades da regi\u00e3o est\u00e3o recebendo a carreata. <strong>Em Altin\u00f3polis, Franca e Jaboticabal ela j\u00e1 ocorreu.<\/strong><\/p>\n<p>Nas cidades de <strong>Araraquara, Batatais, Guar\u00e1, Guariba, Mat\u00e3o, Pontal, Prad\u00f3polis, S\u00e3o Carlos, S\u00e3o Joaquim da Barra e Sert\u00e3ozinho o evento ainda ser\u00e1 realizado<\/strong> <a href=\"https:\/\/www.coca-cola.com.br\/natal?utm_source=google_p&amp;utm_medium=Search&amp;utm_campaign=Meals23Xmas&amp;utm_term=261775701100&amp;utm_content=link&amp;gad_source=1&amp;gclid=CjwKCAiA1MCrBhAoEiwAC2d64Xo-wGrpCHkEPZRSmeY9ZLbPA4SeLaeKKdulKVnvchfDrvoH6QOj_xoCW_IQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\">(clique aqui e veja datas e trajetos).<\/a><\/p>\n<p>A carreta de Natal 2024 da Coca est\u00e1 passando por 22 estados e centenas de munic\u00edpios \u2013 70 cidades s\u00f3 no Estado de S\u00e3o Paulo <a href=\"https:\/\/www.coca-cola.com.br\/natal?utm_source=google_p&amp;utm_medium=Search&amp;utm_campaign=Meals23Xmas&amp;utm_term=261775701100&amp;utm_content=link&amp;gad_source=1&amp;gclid=CjwKCAiA1MCrBhAoEiwAC2d64Xo-wGrpCHkEPZRSmeY9ZLbPA4SeLaeKKdulKVnvchfDrvoH6QOj_xoCW_IQAvD_BwE\" target=\"_blank\" rel=\"noreferrer noopener\">(saiba mais aqui)<\/a>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Confira as datas em Ribeir\u00e3o Preto<\/strong>:<\/h4>\n<p>Pontos de refer\u00eancia: Atacad\u00e3o\/Via Norte \u2013 Av. Mal. Costa e Silva \u2013 Av. Independ\u00eancia \u2013 Choperia Pinguim<\/p>\n<p>Pontos de refer\u00eancia: Novo Shopping\/Av. Pres. Kennedy \u2013 EPTV Ribeir\u00e3o\/ Ipiranga \u2013 Av. Bar\u00e3o do Bananal<\/p>\n<p>Pontos de refer\u00eancia: Av. Prof. Jo\u00e3o Fi\u00fasa \/ Ribeir\u00e3o Shopping \/ Av. Pres. Vargas \/ Av. Independ\u00eancia \/ Av. Le\u00e3o XIII<\/p>\n<p>VEJA TAMB\u00c9M<br \/>Tudo sobre o Coral dos Meninos Cantores em Ribeir\u00e3o Preto<\/p>\n<h4 class=\"wp-block-heading\"><strong>FIQUE ON<\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram\u00a0<\/a>e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp:\u00a0<strong>16 99117 7802.<\/strong><\/p>\n<p>LEIA MAIS<br \/><a href=\"https:\/\/www.tudoep.com\/tudo-receitas\/NOT,0,0,1868324,panetone-de-liquidificador-confira-receita-para-o-natal.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Panetone de liquidificador: confira receita para o Natal<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/saiba-como-ver-as-datas-das-carreatas-de-natal-da-coca-no-interior-de-sp\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] As tradicionais carreatas de Natal, organizadas pela Coca-Cola, j\u00e1 come\u00e7aram. Em Ribeir\u00e3o Preto, os desfiles est\u00e3o programados para os dias 11, 20 e 21 de dezembro. No total, al\u00e9m de Ribeir\u00e3o Preto, treze cidades da regi\u00e3o est\u00e3o recebendo a carreata. Em Altin\u00f3polis, Franca e Jaboticabal ela j\u00e1 ocorreu. Nas cidades de Araraquara, Batatais, Guar\u00e1, &#8230; <a title=\"Saiba como ver as datas das carreatas de Natal da Coca no interior de SP\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/06\/saiba-como-ver-as-datas-das-carreatas-de-natal-da-coca-no-interior-de-sp\/\" aria-label=\"Leia mais sobre Saiba como ver as datas das carreatas de Natal da Coca no interior de SP\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":11562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[1608,1609,265,429,600,237,288,123,1098],"class_list":["post-11561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-carreatas","tag-coca","tag-como","tag-das","tag-datas","tag-interior","tag-natal","tag-saiba","tag-ver"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=1200%2C675&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=1200%2C675&ssl=1",1200,675,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=300%2C169&ssl=1",300,169,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=768%2C432&ssl=1",768,432,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=1024%2C576&ssl=1",1024,576,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=1200%2C675&ssl=1",1200,675,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-06-at-11.29.55.jpeg?fit=1200%2C675&ssl=1",1200,675,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] As tradicionais carreatas de Natal, organizadas pela Coca-Cola, j\u00e1 come\u00e7aram. Em Ribeir\u00e3o Preto, os desfiles est\u00e3o programados para os dias 11, 20 e 21 de dezembro. No total, al\u00e9m de Ribeir\u00e3o Preto, treze cidades da regi\u00e3o est\u00e3o recebendo a carreata. Em Altin\u00f3polis, Franca e Jaboticabal ela j\u00e1 ocorreu. Nas cidades de Araraquara, Batatais, Guar\u00e1,&hellip;","jetpack-related-posts":[{"id":12124,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/ribeirao-preto-tem-shows-gratuitos-de-rock-em-pracas\/","url_meta":{"origin":11561,"position":0},"title":"Ribeir\u00e3o Preto tem shows gratuitos de rock em pra\u00e7as","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto promove, entre os dias 7 e 9 de dezembro, o \u201cKiss Rock nas Pra\u00e7as\u201d, com shows de rock. O evento \u00e9 gratuito e aberto ao p\u00fablico. \u00a0 As apresenta\u00e7\u00f5es acontecem \u00e0s 18h e contam com bandas de rock e DJs, em pra\u00e7as da cidade. \u00a0 Confira a\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-12.51.48.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-12.51.48.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-12.51.48.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-12.51.48.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-12.51.48.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":11892,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/bloco-california-em-ribeirao-preto-confirma-as-primeiras-atracoes\/","url_meta":{"origin":11561,"position":1},"title":"Bloco Calif\u00f3rnia, em Ribeir\u00e3o Preto, confirma as primeiras atra\u00e7\u00f5es","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Bloco Calif\u00f3rnia, em Ribeir\u00e3o Preto, confirmou as primeira atra\u00e7\u00f5es: Tati Quebra Barraco, Carla Cristina e o DJ Blakes. A 7\u00b0 edi\u00e7\u00e3o do evento de pr\u00e9-carnaval acontece em 3 de fevereiro de 2024, no est\u00e1dio Palma Travassos. \u00a0 Segundo a organiza\u00e7\u00e3o do evento j\u00e1 divulgou, o Bloco Calif\u00f3rnia ter\u00e1\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/346244465_1227185564598648_4087334571733265628_n.jpg?fit=1079%2C935&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":13189,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/09\/morre-aos-70-anos-o-professor-mcnamara-da-usp-de-ribeirao-preto\/","url_meta":{"origin":11561,"position":2},"title":"Morre, aos 70 anos, o professor McNamara da USP de Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"9 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Morreu na madrugada da sexta-feira (8), o professor John Campbell McNamara, de 70 anos, titular do Departamento de Biologia e vice-diretor da Faculdade de Filosofia, Ci\u00eancias e Letras de Ribeir\u00e3o Preto (FFCLRP) da USP de Ribeir\u00e3o Preto. Natural da Nova Zel\u00e2ndia, o professor McNamara chegou ao Brasil em 1977\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/John-Campbell-McNamara.webp.webp?fit=1024%2C538&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/John-Campbell-McNamara.webp.webp?fit=1024%2C538&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/John-Campbell-McNamara.webp.webp?fit=1024%2C538&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/John-Campbell-McNamara.webp.webp?fit=1024%2C538&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":79722,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/12\/18\/carreata-de-natal-dos-correios-passa-por-ribeirao-nesta-semana-veja-o-trajeto\/","url_meta":{"origin":11561,"position":3},"title":"Carreata de Natal dos Correios passa por Ribeir\u00e3o nesta semana; Veja o trajeto","author":"ismaelcolosi.com.br","date":"18 de Dezembro de 2024","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe nesta quinta-feira (19), a partir das 19h, a carreata de Natal dos Correios, que vai percorrer os principais pontos do munic\u00edpio. Veja a rota completa abaixo. Os ve\u00edculos iluminados e decorados fazem parte da campanha \u201cPapai Noel dos Correios\u201d, que tamb\u00e9m promove a ado\u00e7\u00e3o de cartinhas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Anotacao-2024-11-28-134812_2024-12-18_18-13-07_png_2024-12-18_18-13-07.webp.webp?fit=758%2C338&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Anotacao-2024-11-28-134812_2024-12-18_18-13-07_png_2024-12-18_18-13-07.webp.webp?fit=758%2C338&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Anotacao-2024-11-28-134812_2024-12-18_18-13-07_png_2024-12-18_18-13-07.webp.webp?fit=758%2C338&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/12\/Anotacao-2024-11-28-134812_2024-12-18_18-13-07_png_2024-12-18_18-13-07.webp.webp?fit=758%2C338&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2057,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/14\/ribeirao-preto-recebe-carreata-com-pilotos-do-brasileiro-de-drift\/","url_meta":{"origin":11561,"position":4},"title":"Ribeir\u00e3o Preto recebe carreata com pilotos do Brasileiro de Drift\u00a0","author":"ismaelcolosi.com.br","date":"14 de Novembro de 2023","format":false,"excerpt":"[ad_1] Ribeir\u00e3o Preto recebe, na quinta-feira (16), \u00e0s 19 horas, uma carreata com pilotos que ir\u00e3o participar da final do Campeonato Brasileiro de Drift \u2013 o Ultimate Drift. A sa\u00edda ser\u00e1 do Est\u00e1dio Palma Travassos. \u00a0 A a\u00e7\u00e3o conta com 10 competidores com carros esportivos. A carreta vai passar pelas\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/393173390_1147405786236967_5512402464779497998_n-1.jpg?fit=1080%2C720&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/393173390_1147405786236967_5512402464779497998_n-1.jpg?fit=1080%2C720&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/393173390_1147405786236967_5512402464779497998_n-1.jpg?fit=1080%2C720&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/393173390_1147405786236967_5512402464779497998_n-1.jpg?fit=1080%2C720&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/393173390_1147405786236967_5512402464779497998_n-1.jpg?fit=1080%2C720&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":5446,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/23\/confira-as-datas-da-caravana-de-natal-da-coca-cola-em-ribeirao\/","url_meta":{"origin":11561,"position":5},"title":"Confira as datas da Caravana de Natal da Coca-Cola em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"23 de Novembro de 2023","format":false,"excerpt":"[ad_1] A tradicional Caravana de Natal da Coca-Cola foi confirmada em Ribeir\u00e3o Preto. De acordo com a empresa, a comitiva com os carros iluminados e com o Papai Noel passar\u00e1 pelo munic\u00edpio nos dias 11, 20 e 21 de dezembro. Neste ano, o tema central da campanha \u2018Desperte o Papai\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/carreata_natal_1024x576_20122019154323.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/carreata_natal_1024x576_20122019154323.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/carreata_natal_1024x576_20122019154323.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/carreata_natal_1024x576_20122019154323.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-30t","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11561"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/11562"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}