{"id":11216,"date":"2023-12-05T19:27:54","date_gmt":"2023-12-05T22:27:54","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/tudo-sobre-o-concerto-de-natal-da-casa-da-memoria-italiana-de-ribeirao-preto\/"},"modified":"2023-12-05T19:27:54","modified_gmt":"2023-12-05T22:27:54","slug":"tudo-sobre-o-concerto-de-natal-da-casa-da-memoria-italiana-de-ribeirao-preto","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/tudo-sobre-o-concerto-de-natal-da-casa-da-memoria-italiana-de-ribeirao-preto\/","title":{"rendered":"Tudo sobre o Concerto de Natal da Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o Preto"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O<strong> 8\u00ba Concerto di Natale<\/strong>, tradicional evento natalino do <strong>Museu Casa da Mem\u00f3ria Italiana<\/strong> de <strong>Ribeir\u00e3o Preto<\/strong>, acontece nesta quarta-feira (6).<\/p>\n<p>De acordo com a organiza\u00e7\u00e3o, a apresenta\u00e7\u00e3o <mark style=\"background-color:#fcb900\" class=\"has-inline-color\">promove momentos sens\u00edveis e art\u00edsticos para todos aqueles que estiverem presentes e tamb\u00e9m para o centro da cidade<\/mark>. Confira tudo o que voc\u00ea precisa saber sobre o concerto:<\/p>\n<h4 class=\"wp-block-heading\"><strong>Hor\u00e1rio e entrada<\/strong><\/h4>\n<p>O <strong>Concerto de Natal do Museu Casa da Mem\u00f3ria Italiana<\/strong> acontece a partir das <strong>19h30<\/strong>. O <strong>evento \u00e9 gratuito<\/strong> e indicado para todas as idades e p\u00fablicos.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Onde ser\u00e1 a apresenta\u00e7\u00e3o?<\/strong><\/h4>\n<p>A apresenta\u00e7\u00e3o acontece nos <strong>jardins da fachada do museu<\/strong>, na rua Tibiri\u00e7\u00e1, 776, no Centro de Ribeir\u00e3o Preto. O local <strong>acolhe todas as pessoas em frente ao patrim\u00f4nio hist\u00f3rico e cultural<\/strong> da cidade.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Quem se apresenta?<\/strong><\/h4>\n<p>O <strong>Concerto di Natale<\/strong> apresenta o <strong>Coro Memorie d\u2019Italia<\/strong>, com reg\u00eancia do maestro <strong>Alexandre Mazzer Perticarrari<\/strong>.<\/p>\n<p>O coro \u00e9 um parceiro da <strong>Casa da Mem\u00f3ria Italiana<\/strong>, desde 2015, e utiliza semanalmente as depend\u00eancias do local como espa\u00e7o de <strong>ensaio e estudo das can\u00e7\u00f5es italianas<\/strong>.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Qual ser\u00e1 o repert\u00f3rio?<\/strong><\/h4>\n<p>O repert\u00f3rio do tradicional concerto contar\u00e1 com <strong>m\u00fasicas que recordam a imigra\u00e7\u00e3o e a cultura tradicional italiana<\/strong>, al\u00e9m de alguns <strong>cl\u00e1ssicos natalinos<\/strong>, fazendo encontrar o passado no presente.<\/p>\n<h4 class=\"wp-block-heading\"><strong>Previs\u00e3o do tempo<\/strong><\/h4>\n<p>De acordo com a plataforma <strong>Climatempo<\/strong>, Ribeir\u00e3o Preto deve ter temperatura <strong>m\u00e1xima de 34\u00b0C<\/strong> nesta quarta-feira (6), com m\u00ednima de 21\u00b0C.\u00a0O dia deve ser de Sol com o aumento de nuvens pela manh\u00e3, com pancadas de chuva nos per\u00edodos da tarde e da noite.<\/p>\n<p>VEJA TAMB\u00c9M<\/p>\n<p>Coral realiza apresenta\u00e7\u00f5es gratuitas de Natal em Ribeir\u00e3o Preto\u00a0<\/p>\n<h4 class=\"wp-block-heading\"><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color\">FIQUE ON<\/mark><\/strong><\/h4>\n<p>Fique ligado em tudo que acontece em Ribeir\u00e3o Preto e regi\u00e3o. Siga os perfis do\u00a0<strong>acidade on<\/strong>\u00a0no\u00a0<a href=\"https:\/\/www.instagram.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>\u00a0e no\u00a0<a href=\"https:\/\/www.facebook.com\/acidadeonribeirao\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook.<\/a><\/p>\n<p>Receba not\u00edcias do\u00a0<strong>acidade on<\/strong>\u00a0no WhatsApp.<a href=\"https:\/\/chat.whatsapp.com\/Bnv2w66ZT4VDyZW3oiZ69n\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Para entrar no grupo, basta clicar aqui.<\/a><\/p>\n<p>Fa\u00e7a uma den\u00fancia ou sugira uma reportagem sobre a Ribeir\u00e3o Preto e regi\u00e3o pelo WhatsApp: (16) 99117 7802.<\/p>\n<p>LEIA MAIS<\/p>\n<p><a href=\"https:\/\/www.tudoep.com\/tudo-valor\/NOT,0,0,1868522,jornada-de-trabalho-sera-reduzida-no-brasil-entenda-a-pec.aspx\" target=\"_blank\" rel=\"noreferrer noopener\">Jornada de trabalho ser\u00e1 reduzida no Brasil? Entenda a PEC<\/a><\/p>\n<p><!-- AI CONTENT END 1 -->\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/www.acidadeon.com\/ribeiraopreto\/lazer-e-cultura\/tudo-sobre-o-concerto-de-natal-da-casa-da-memoria-italiana-de-ribeirao-preto\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O 8\u00ba Concerto di Natale, tradicional evento natalino do Museu Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o Preto, acontece nesta quarta-feira (6). De acordo com a organiza\u00e7\u00e3o, a apresenta\u00e7\u00e3o promove momentos sens\u00edveis e art\u00edsticos para todos aqueles que estiverem presentes e tamb\u00e9m para o centro da cidade. Confira tudo o que voc\u00ea precisa saber sobre &#8230; <a title=\"Tudo sobre o Concerto de Natal da Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o Preto\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/05\/tudo-sobre-o-concerto-de-natal-da-casa-da-memoria-italiana-de-ribeirao-preto\/\" aria-label=\"Leia mais sobre Tudo sobre o Concerto de Natal da Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o Preto\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":11217,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[289,287,291,290,288,27,26,468,43],"class_list":["post-11216","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi","tag-casa","tag-concerto","tag-italiana","tag-memoria","tag-natal","tag-preto","tag-ribeirao","tag-sobre","tag-tudo"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=1024%2C683&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=1024%2C683&ssl=1",1024,683,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=300%2C200&ssl=1",300,200,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=768%2C512&ssl=1",768,512,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=1024%2C683&ssl=1",1024,683,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=1024%2C683&ssl=1",1024,683,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/Memoria-Italiana.jpg?fit=1024%2C683&ssl=1",1024,683,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O 8\u00ba Concerto di Natale, tradicional evento natalino do Museu Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o Preto, acontece nesta quarta-feira (6). De acordo com a organiza\u00e7\u00e3o, a apresenta\u00e7\u00e3o promove momentos sens\u00edveis e art\u00edsticos para todos aqueles que estiverem presentes e tamb\u00e9m para o centro da cidade. Confira tudo o que voc\u00ea precisa saber sobre&hellip;","jetpack-related-posts":[{"id":3405,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/18\/concerto-de-natal-da-casa-da-memoria-italiana-de-ribeirao-ja-tem-data-confira\/","url_meta":{"origin":11216,"position":0},"title":"Concerto de Natal da Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o j\u00e1 tem data; Confira","author":"ismaelcolosi.com.br","date":"18 de Novembro de 2023","format":false,"excerpt":"[ad_1] O Concerto de Natal do Museu Casa da Mem\u00f3ria Italiana de Ribeir\u00e3o Preto j\u00e1 tem data marcada. O evento aconteceu no dia 6 de dezembro, a partir das 19h30. A apresenta\u00e7\u00e3o contar\u00e1 com o Coro Memorie d\u2019Italia, regido pelo maestro Alexandre Mazzer Perticarrari. O repert\u00f3rio contar\u00e1 com m\u00fasicas que\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concerto-de-natal.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concerto-de-natal.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concerto-de-natal.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concerto-de-natal.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/concerto-de-natal.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12038,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/confira-fotos-do-coral-de-natal-no-centro-de-ribeirao-veja-outras-apresentacoes\/","url_meta":{"origin":11216,"position":1},"title":"Confira fotos do coral de Natal no Centro de Ribeir\u00e3o; Veja outras apresenta\u00e7\u00f5es","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O museu Casa da Mem\u00f3ria Italiana, no Centro de Ribeir\u00e3o Preto, realizou, na noite desta quarta-feira (6), a 8\u00aa edi\u00e7\u00e3o do Concerto di Natale. A apresenta\u00e7\u00e3o contou com a presen\u00e7a de centenas de pessoas. Por cerca de uma hora, o p\u00fablico cantou v\u00e1rios cl\u00e1ssicos natalinos em italiano. O museu\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-09.25.57-1.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-09.25.57-1.jpeg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-09.25.57-1.jpeg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-09.25.57-1.jpeg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-07-at-09.25.57-1.jpeg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8235,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/29\/tudo-o-que-voce-precisa-saber-sobre-o-natal-no-centro-de-ribeirao-preto\/","url_meta":{"origin":11216,"position":2},"title":"Tudo o que voc\u00ea precisa saber sobre o Natal no Centro de Ribeir\u00e3o Preto\u00a0","author":"ismaelcolosi.com.br","date":"29 de Novembro de 2023","format":false,"excerpt":"[ad_1] O primeiro final de semana do m\u00eas de dezembro marca o in\u00edcio das celebra\u00e7\u00f5es natalinas realizadas no Centro de Ribeir\u00e3o Preto. \u00a0 O acidadeon preparou uma programa\u00e7\u00e3o do que voc\u00ea precisa saber para aproveitar o Natal e os eventos comemorativos no Cal\u00e7ad\u00e3o e regi\u00e3o.\u00a0 HOR\u00c1RIO DE FUNCIONAMENTO\u00a0 A Acirp\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe","width":350,"height":200,"srcset":"https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 1x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 1.5x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 2x, https:\/\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/whatsapp_image_2022-12-06_at_09_32_39.jpe 3x"},"classes":[]},{"id":4464,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/21\/natal-tudo-sobre-o-coral-dos-meninos-cantores-em-ribeirao-preto\/","url_meta":{"origin":11216,"position":3},"title":"Natal: Tudo sobre o Coral dos Meninos Cantores em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"21 de Novembro de 2023","format":false,"excerpt":"[ad_1] A 26\u00b0 edi\u00e7\u00e3o do Coral dos Meninos Cantores da Cia Minaz, uma das apresenta\u00e7\u00f5es natalinas mais tradicionais de Ribeir\u00e3o Preto, acontece no dia 17 de dezembro, \u00e0s 20h. As meninas e meninos cantores ficam nas janelas do Edif\u00edcio Meira Junior, na choperia Pinguim, no Centro, entoando cl\u00e1ssicos do Natal.\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/coral_natal.jpg?fit=1200%2C675&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/coral_natal.jpg?fit=1200%2C675&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/coral_natal.jpg?fit=1200%2C675&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/coral_natal.jpg?fit=1200%2C675&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/coral_natal.jpg?fit=1200%2C675&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3921,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/11\/20\/ribeirao-preto-recebe-festival-de-curtas-metragens-cine-zumbido-neste-feriado\/","url_meta":{"origin":11216,"position":4},"title":"Ribeir\u00e3o Preto recebe festival de curtas-metragens &#8216;Cine Zumbido&#8217; neste feriado","author":"ismaelcolosi.com.br","date":"20 de Novembro de 2023","format":false,"excerpt":"[ad_1] A Prefeitura de Ribeir\u00e3o Preto realiza, nesta segunda-feira (20), \u00e0s 18h30, no Centro Cultural Palace, a Mostra de Cinema \u2018Cine Zumbido\u2019. O evento \u00e9 gratuito e aberto ao p\u00fablico. A iniciativa faz parte da programa\u00e7\u00e3o do M\u00eas da Consci\u00eancia Negra e \u00e9 realizado atrav\u00e9s das secretarias da Cultura e\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/centro_cultural_1024x576_14022020200647.jpg?fit=1024%2C576&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/centro_cultural_1024x576_14022020200647.jpg?fit=1024%2C576&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/centro_cultural_1024x576_14022020200647.jpg?fit=1024%2C576&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/11\/centro_cultural_1024x576_14022020200647.jpg?fit=1024%2C576&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":29782,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2024\/01\/19\/quermesse-encontro-de-fuscas-e-musica-veja-as-opcoes-para-aproveitar-o-final-de-semana-em-ribeirao-preto\/","url_meta":{"origin":11216,"position":5},"title":"Quermesse, encontro de Fuscas e m\u00fasica: Veja as op\u00e7\u00f5es para aproveitar o final de semana em Ribeir\u00e3o Preto","author":"ismaelcolosi.com.br","date":"19 de Janeiro de 2024","format":false,"excerpt":"[ad_1] Quem for passar o final de semana em Ribeir\u00e3o Preto ter\u00e1 diversas op\u00e7\u00f5es de cultura e lazer. Tem quermesse, encontro de Fuscas e muita m\u00fasica. Al\u00e9m disso, o Bosque F\u00e1bio Barreto e o Museu Casa da Mem\u00f3ria Italiana, contam com programa\u00e7\u00e3o de f\u00e9rias para a crian\u00e7ada. Confira a programa\u00e7\u00e3o:\u2026","rel":"","context":"In &quot;Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o&quot;","block_context":{"text":"Not\u00edcias de Ribeir\u00e3o Preto-SP e Regi\u00e3o","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/noticias-de-ribeirao-preto-sp-e-regiao-ismael-colosi\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Design-sem-nome.jpg?fit=811%2C491&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Design-sem-nome.jpg?fit=811%2C491&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Design-sem-nome.jpg?fit=811%2C491&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2024\/01\/Design-sem-nome.jpg?fit=811%2C491&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-2UU","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11216"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/11217"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}