{"id":10350,"date":"2023-12-04T11:42:27","date_gmt":"2023-12-04T14:42:27","guid":{"rendered":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/governo-quer-ampliar-valor-da-aposentadoria-pelo-inss\/"},"modified":"2023-12-04T11:42:27","modified_gmt":"2023-12-04T14:42:27","slug":"governo-quer-ampliar-valor-da-aposentadoria-pelo-inss","status":"publish","type":"post","link":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/governo-quer-ampliar-valor-da-aposentadoria-pelo-inss\/","title":{"rendered":"Governo quer ampliar valor da aposentadoria pelo INSS"},"content":{"rendered":"<p> [ad_1]<br \/>\n<\/p>\n<div>\n<p>O Ministro do Empreendedorismo, <a href=\"https:\/\/catracalivre.com.br\/cidadania\/eleicoes-2020-o-que-voce-precisa-saber-sobre-marcio-franca\/\" target=\"_blank\" rel=\"noopener\">M\u00e1rcio Fran\u00e7a<\/a> (PSB), revelou planos para reformular as regras de faturamento do <a href=\"https:\/\/catracalivre.com.br\/cidadania\/abrir-mei-fica-ainda-mais-simples-apos-esta-decisao-do-governo-confira\/\" target=\"_blank\" rel=\"noopener\">Microempreendedor Individual<\/a> (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os <a href=\"https:\/\/catracalivre.com.br\/empreendedorismo-real\/\" target=\"_blank\" rel=\"noopener\">empreendedores<\/a> a contribuir mais para a <a href=\"https:\/\/catracalivre.com.br\/cidadania\/previdencia-emprestimo\/\" target=\"_blank\" rel=\"noopener\">Previd\u00eancia<\/a>, o que resultaria em benef\u00edcios de <a href=\"https:\/\/catracalivre.com.br\/cidadania\/senado-aprova-novo-criterio-especial-para-aposentadoria-saiba-qual\/\" target=\"_blank\" rel=\"noopener\">aposentadoria<\/a> mais substanciais.<\/p>\n<div id=\"attachment_2316285\" class=\"wp-caption aligncenter\">\n<div class=\"d-flex justify-content-center\" data-attachment-id=\"2316285\">\n<div class=\"position-relative d-inline-block\"><img data-recalc-dims=\"1\" data-portal-copyright=\"Istock\/FG Trade\" fetchpriority=\"high\" decoding=\"async\" class=\"size-large wp-image-2316285\" src=\"https:\/\/i0.wp.com\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853-910x608.jpg?resize=910%2C608&#038;ssl=1\" alt=\"MEI: Governo quer ampliar valor da aposentadoria pelo INSS\" width=\"910\" height=\"608\" srcset=\"https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853-910x608.jpg 910w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853-450x301.jpg 450w, https:\/\/catracalivre.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853-768x513.jpg 768w\" sizes=\"(max-width: 910px) 100vw, 910px\"\/><\/p>\n<p>Cr\u00e9ditos: Istock\/FG Trade<\/p>\n<\/div>\n<\/div>\n<p><span class=\"post-imagem__legenda\">MEI: Governo quer ampliar valor da aposentadoria pelo INSS<\/span><\/p>\n<\/div>\n<p>O ministro est\u00e1 considerando a cria\u00e7\u00e3o de um sistema de impostos baseado em uma tabela de faturamento mensal.<\/p>\n<p>Essa declara\u00e7\u00e3o foi feita durante a segunda reuni\u00e3o ordin\u00e1ria do F\u00f3rum Permanente das Microempresas e Empresas de Pequeno Porte (<a href=\"https:\/\/www.gov.br\/empresas-e-negocios\/pt-br\/forum-permanente\" target=\"_blank\" rel=\"noopener\">FPMPE<\/a>), que ocorreu no edif\u00edcio-sede da CNC em Bras\u00edlia. O evento contou com a presen\u00e7a do presidente interino,<a href=\"https:\/\/catracalivre.com.br\/cidadania\/alckmin-choca-brasileiros-e-explica-por-que-acredita-que-dolar-a-r-5-e-bom\/\" target=\"_blank\" rel=\"noopener\"> Geraldo Alckmin<\/a> (PSB).<\/p>\n<p>O limite atual de faturamento para o MEI \u00e9 de R$ 81.000 por ano, com o valor do Documento de Arrecada\u00e7\u00e3o do Simples Nacional (DAS) variando entre R$ 67 e R$ 72, dependendo da atividade do microempreendedor. Esse montante inclui tributos como o INSS, correspondente a um sal\u00e1rio m\u00ednimo.<\/p>\n<p>Com a poss\u00edvel mudan\u00e7a, a ideia \u00e9 que, ao contribuir mais, o MEI possa aspirar a uma aposentadoria que ultrapasse o valor de um sal\u00e1rio m\u00ednimo. M\u00e1rcio Fran\u00e7a acredita que essa altera\u00e7\u00e3o pode contribuir para aliviar os desafios financeiros da Previd\u00eancia.<\/p>\n<p>\u201cN\u00e3o vai resolver todos os problemas, mas se mais pessoas contribu\u00edrem com quantias maiores, isso certamente reduzir\u00e1 o d\u00e9ficit\u201d, afirmou o ministro.<\/p>\n<h2>Cr\u00e9dito para MEI<\/h2>\n<p>Al\u00e9m disso, Fran\u00e7a defendeu a cria\u00e7\u00e3o de um fundo garantidor de cr\u00e9dito para facilitar empr\u00e9stimos destinados aos pequenos empreendedores, com o objetivo de incentivar a formaliza\u00e7\u00e3o dos trabalhadores informais.<\/p>\n<p>Ele destacou a necessidade de estabelecer linhas de financiamento que envolvam todos os bancos do pa\u00eds, tanto privados quanto p\u00fablicos.<\/p>\n<p>A proposta de criar um fundo garantidor para microempreendedores tamb\u00e9m recebeu apoio de Geraldo Alckmin. \u201cO cr\u00e9dito, dependendo dos juros, pode n\u00e3o ser a solu\u00e7\u00e3o e se tornar um problema. Precisamos nos concentrar em um fundo garantidor\u201d, ressaltou o presidente interino.<\/p>\n<h2>Transi\u00e7\u00e3o de MEI para microempresa<\/h2>\n<p>Em rela\u00e7\u00e3o \u00e0 transi\u00e7\u00e3o do MEI, Fran\u00e7a indicou que as novas regras, planejadas para entrar em vigor a partir de 2024, buscam tributar apenas a parcela que excede o limite de faturamento do MEI.<\/p>\n<p>Atualmente, se o faturamento ultrapassar R$ 81.000 por ano, o empreendedor \u00e9 obrigado a migrar para o regime tribut\u00e1rio de microempresa. A ideia \u00e9 tributar apenas o valor excedente ao limite, evitando uma mudan\u00e7a autom\u00e1tica de regime tribut\u00e1rio para o MEI.<\/p>\n<p>Atualmente se o faturamento foi de at\u00e9 20% acima do limite (ou seja, at\u00e9 R$ 97.200,00): o MEI pode permanecer no Simples Nacional, mas no ano seguinte ser\u00e1 desenquadrado da condi\u00e7\u00e3o de MEI.<\/p>\n<p>Agora, se o faturamento foi mais de 20% acima do limite: o MEI ser\u00e1 desenquadrado, passar\u00e1 \u00e0 condi\u00e7\u00e3o de microempresa e ser\u00e1 tributado com base no Simples Nacional retroativamente ao in\u00edcio do ano \u2013isto \u00e9, ser\u00e1 cobrado imposto em todas as notas emitidas no ano\u00a0em que ocorreu o excesso.<\/p>\n<\/div>\n<p><script>\n\t\t! function(f, b, e, v, n, t, s) {\n\t\t\tif (f.fbq) return;\n\t\t\tn = f.fbq = function() {\n\t\t\t\tn.callMethod ?\n\t\t\t\t\tn.callMethod.apply(n, arguments) : n.queue.push(arguments)\n\t\t\t};\n\t\t\tif (!f._fbq) f._fbq = n;\n\t\t\tn.push = n;\n\t\t\tn.loaded = !0;\n\t\t\tn.version = '2.0';\n\t\t\tn.queue = [];\n\t\t\tt = b.createElement(e);\n\t\t\tt.async = !0;\n\t\t\tt.src = v;\n\t\t\ts = b.getElementsByTagName(e)[0];\n\t\t\ts.parentNode.insertBefore(t, s)\n\t\t}(window, document, 'script',\n\t\t\t'https:\/\/connect.facebook.net\/en_US\/fbevents.js');\n\t\tfbq('init', '338315473262380');\n\t\tfbq('track', 'PageView');\n\t<\/script><br \/>\n<br \/>[ad_2]<br \/>\n<br \/><a href=\"https:\/\/catracalivre.com.br\/cidadania\/mei-governo-quer-ampliar-valor-da-aposentadoria-pelo-inss\/\" target=\"_blank\" rel=\"noopener\">Source link <\/a><\/p>\n<div class='code-block code-block-4' style='margin: 8px auto 8px 0; text-align: left; display: block; clear: both;'>\n\ud83d\udce2 Aviso Legal\n\nO site ismaelcolosi.com.br atua apenas como um canal de divulga\u00e7\u00e3o de oportunidades de emprego e n\u00e3o se responsabiliza pelo processo seletivo, contrata\u00e7\u00e3o ou qualquer outra etapa relacionada \u00e0s vagas publicadas. Todas as informa\u00e7\u00f5es s\u00e3o de responsabilidade dos anunciantes.\n\n\u26a0\ufe0f Aten\u00e7\u00e3o! Nunca pague por promessas de emprego nem compre cursos que garantam contrata\u00e7\u00e3o. Desconfie de qualquer cobran\u00e7a para participar de sele\u00e7\u00f5es.\n\n\n\n<\/div>\n<!-- CONTENT END 1 -->\n","protected":false},"excerpt":{"rendered":"<p>[ad_1] O Ministro do Empreendedorismo, M\u00e1rcio Fran\u00e7a (PSB), revelou planos para reformular as regras de faturamento do Microempreendedor Individual (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os empreendedores a contribuir mais para a Previd\u00eancia, o que resultaria em benef\u00edcios de aposentadoria mais substanciais. Cr\u00e9ditos: Istock\/FG Trade MEI: Governo quer ampliar valor da aposentadoria pelo INSS &#8230; <a title=\"Governo quer ampliar valor da aposentadoria pelo INSS\" class=\"read-more\" href=\"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/governo-quer-ampliar-valor-da-aposentadoria-pelo-inss\/\" aria-label=\"Leia mais sobre Governo quer ampliar valor da aposentadoria pelo INSS\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":10351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-10350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-variedades"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=1200%2C638&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=1200%2C638&ssl=1",1200,638,false],"thumbnail":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=300%2C160&ssl=1",300,160,true],"medium_large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=768%2C408&ssl=1",768,408,true],"large":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=1024%2C544&ssl=1",1024,544,true],"1536x1536":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=1200%2C638&ssl=1",1200,638,true],"2048x2048":["https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1423350853.jpg?fit=1200%2C638&ssl=1",1200,638,true]},"uagb_author_info":{"display_name":"ismaelcolosi.com.br","author_link":"https:\/\/ismaelcolosi.com.br\/author\/vidareal-online\/"},"uagb_comment_info":0,"uagb_excerpt":"[ad_1] O Ministro do Empreendedorismo, M\u00e1rcio Fran\u00e7a (PSB), revelou planos para reformular as regras de faturamento do Microempreendedor Individual (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os empreendedores a contribuir mais para a Previd\u00eancia, o que resultaria em benef\u00edcios de aposentadoria mais substanciais. Cr\u00e9ditos: Istock\/FG Trade MEI: Governo quer ampliar valor da aposentadoria pelo INSS&hellip;","jetpack-related-posts":[{"id":10688,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/mei-podera-aumentar-o-valor-da-aposentadoria-pelo-inss-confira\/","url_meta":{"origin":10350,"position":0},"title":"MEI poder\u00e1 aumentar o valor da aposentadoria pelo INSS? Confira","author":"ismaelcolosi.com.br","date":"4 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Ministro do Empreendedorismo, M\u00e1rcio Fran\u00e7a (PSB), revelou planos para reformular as regras de faturamento do Microempreendedor Individual (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os empreendedores a contribuir mais para a Previd\u00eancia, o que resultaria em benef\u00edcios de aposentadoria mais substanciais. Cr\u00e9ditos: Istock\/JLco - Julia AmaralMEI poder\u00e1 aumentar\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1690799866.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1690799866.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1690799866.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1690799866.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1690799866.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12519,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/08\/governo-quer-ampliar-faturamento-do-mei-com-beneficios-confira\/","url_meta":{"origin":10350,"position":1},"title":"Governo quer ampliar faturamento do MEI com benef\u00edcios; confira","author":"ismaelcolosi.com.br","date":"8 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Ministro do Empreendedorismo, M\u00e1rcio Fran\u00e7a (PSB), revelou planos para reformular as regras de faturamento do Microempreendedor Individual (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os empreendedores a contribuir mais para a Previd\u00eancia, o que resultaria em benef\u00edcios de aposentadoria mais substanciais. Cr\u00e9ditos: Istock\/FG TradeMEI: Governo quer ampliar valor\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702029531_istock-1423350853.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702029531_istock-1423350853.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702029531_istock-1423350853.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702029531_istock-1423350853.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1702029531_istock-1423350853.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":20316,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/25\/havera-novos-beneficios-para-o-empreendedor\/","url_meta":{"origin":10350,"position":2},"title":"haver\u00e1 novos benef\u00edcios para o empreendedor?","author":"ismaelcolosi.com.br","date":"25 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Istock\/JLco - Julia AmaralGoverno promete facilitar a vida do MEI com estas medidas O ano de 2024 se apresenta como um per\u00edodo de poss\u00edveis mudan\u00e7as significativas para o Microempreendedor Individual (MEI), especialmente no que diz respeito \u00e0 previd\u00eancia do empreendedor. Recentemente, o governo anunciou uma proposta que visa\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703474238_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703474238_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703474238_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703474238_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1703474238_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":10252,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/04\/veja-a-proposta-de-aumento-de-faturamento-para-mei\/","url_meta":{"origin":10350,"position":3},"title":"Veja a proposta de aumento de faturamento para MEI","author":"ismaelcolosi.com.br","date":"4 de Dezembro de 2023","format":false,"excerpt":"[ad_1] Cr\u00e9ditos: Istock\/KerkezMEI: Descubra as novidades EXTRAORDIN\u00c1RIAS O ministro M\u00e1rcio Fran\u00e7a, trouxe \u00e0 tona a discuss\u00e3o sobre o aumento dos limites de faturamento para o Microempreendedor Individual (MEI) e para o Simples Nacional. A proposta visa n\u00e3o apenas beneficiar os empreendedores em suas opera\u00e7\u00f5es di\u00e1rias, mas tamb\u00e9m impactar positivamente em\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/atencao-o-governo-nao-enquadra-mais-essas-atividades-como-mei.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/atencao-o-governo-nao-enquadra-mais-essas-atividades-como-mei.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/atencao-o-governo-nao-enquadra-mais-essas-atividades-como-mei.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/atencao-o-governo-nao-enquadra-mais-essas-atividades-como-mei.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/atencao-o-governo-nao-enquadra-mais-essas-atividades-como-mei.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":14018,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/11\/governo-surpeende-com-mudancas-drasticas-para-quem-e-mei\/","url_meta":{"origin":10350,"position":4},"title":"Governo SURPEENDE com mudan\u00e7as DR\u00c1STICAS para quem \u00e9 MEI","author":"ismaelcolosi.com.br","date":"11 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Ministro do Empreendedorismo, M\u00e1rcio Fran\u00e7a (PSB), revelou planos para reformular as regras de faturamento do Microempreendedor Individual (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os empreendedores a contribuir mais para a Previd\u00eancia, o que resultaria em benef\u00edcios de aposentadoria mais substanciais. Cr\u00e9ditos: Istock\/klebercordeiroGoverno SURPEENDE com mudan\u00e7as DR\u00c1STICAS para\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1417064302.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1417064302.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1417064302.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1417064302.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/istock-1417064302.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":12325,"url":"https:\/\/ismaelcolosi.com.br\/index.php\/2023\/12\/07\/mudancas-na-transicao-de-mei-para-microempresa-chegam-em-breve\/","url_meta":{"origin":10350,"position":5},"title":"Mudan\u00e7as na transi\u00e7\u00e3o de MEI para microempresa chegam em breve","author":"ismaelcolosi.com.br","date":"7 de Dezembro de 2023","format":false,"excerpt":"[ad_1] O Ministro do Empreendedorismo, M\u00e1rcio Fran\u00e7a (PSB), revelou planos para reformular as regras de faturamento do Microempreendedor Individual (MEI). Segundo Fran\u00e7a, a proposta visa incentivar os empreendedores a contribuir mais para a Previd\u00eancia, o que resultaria em benef\u00edcios de aposentadoria mais substanciais. Cr\u00e9ditos: Istock\/FG TradeMudan\u00e7as na transi\u00e7\u00e3o de MEI\u2026","rel":"","context":"In &quot;Variedades&quot;","block_context":{"text":"Variedades","link":"https:\/\/ismaelcolosi.com.br\/index.php\/category\/variedades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1701990248_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1701990248_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1701990248_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1701990248_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/ismaelcolosi.com.br\/wp-content\/uploads\/2023\/12\/1701990248_istock-1416831637.jpg?fit=1200%2C638&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pfMlyK-2GW","_links":{"self":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=10350"}],"version-history":[{"count":0,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/posts\/10350\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media\/10351"}],"wp:attachment":[{"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=10350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=10350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ismaelcolosi.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=10350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}